{"id":263534,"date":"2025-12-16T12:01:55","date_gmt":"2025-12-16T15:01:55","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=263534"},"modified":"2025-12-16T12:32:54","modified_gmt":"2025-12-16T15:32:54","slug":"luis-enrique-psg-flamengo","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/luis-enrique-psg-flamengo\/","title":{"rendered":"Luis Enrique elogia Flamengo e cita motiva\u00e7\u00e3o no PSG: &#8220;Queremos fazer hist\u00f3ria&#8221;"},"content":{"rendered":"\n<p><strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/fifa-intercontinental-cup-8268\/flamengo-psg-480-1215-8268#id=4630907\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo e PSG se enfrentam<\/a><\/strong> nesta quarta-feira (17), \u00e0s 14h (de Bras\u00edlia), no Catar, pela final da <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/category\/futebol-internacional\/intercontinental-clubes\/\" target=\"_blank\" rel=\"noreferrer noopener\">Copa Intercontinental de Clubes<\/a><\/strong>. O t\u00e9cnico Luis Enrique concedeu entrevista coletiva e falou sobre o confronto entre as equipes.<\/p>\n\n\n\n<p>Ansioso pelo embate com o representante brasileiro no Mundial, o treinador espanhol <strong>elogiou a equipe carioca<\/strong>, principalmente pelo estilo de jogo do t\u00e9cnico Filipe Lu\u00eds. Ainda, <strong>relembrou a derrota contra o Botafogo<\/strong> e fez compara\u00e7\u00f5es com as maneiras de jogar.<\/p>\n\n\n\n<p>&#8220;Tivemos temporadas diferentes. O <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/flamengo-1215\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo<\/a><\/strong> ganhou muitos trof\u00e9us e est\u00e1 muito bem. Gosto do jeito como eles jogam, com e sem a bola. S\u00e3o muito bem treinados. Vimos a campanha deles na Copa do Mundo de Clubes. (Flamengo) Vai ser um advers\u00e1rio muito dif\u00edcil de se jogar contra e sabemos disso.&#8221;, afirmou o treinador, em entrevista coletiva.<\/p>\n\n\n\n<p>&#8220;O jogo contra o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/botafogo-1211\" target=\"_blank\" rel=\"noreferrer noopener\">Botafogo <\/a><\/strong>foi dif\u00edcil, eles se defenderam o tempo todo e n\u00e3o conseguimos furar a defesa. O Flamengo joga diferente, jogam um futebol muito bom. Jogam desde o campo de defesa e pressionam sem a bola. \u00c9 um time muito interessante com jogadores capacitados que sabem jogar grandes partidas. Vai ser uma final aberta pois temos estilos parecidos.&#8221;, completou.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">AO VIVO: Acompanhe a coletiva de Luis Enrique na v\u00e9spera do confronto com o Flamengo \ud83c\udf99\ufe0f<a href=\"https:\/\/t.co\/9I3Tk7qxaD\">https:\/\/t.co\/9I3Tk7qxaD<\/a><\/p>&mdash; Paris Saint-Germain (@PSGbrasil) <a href=\"https:\/\/twitter.com\/PSGbrasil\/status\/2000929794566025519?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 16, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Historicamente, a disputa da Copa Intercontinental tem um peso maior para o futebol nas Am\u00e9ricas do que para a Europa. No entanto, Luis Enrique afirmou que o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/psg-480\" target=\"_blank\" rel=\"noreferrer noopener\">PSG <\/a>est\u00e1 totalmente motivado<\/strong> para ir em busca do t\u00edtulo, que seria o primeiro da categoria na sala de trof\u00e9us do clube franc\u00eas.<\/p>\n\n\n\n<p>&#8220;A motiva\u00e7\u00e3o sempre existe. Fizemos hist\u00f3ria com o PSG no ano passado e queremos fazer de novo. Toda final \u00e9 diferente e especial. \u00c9 preciso estar focado, pois cada momento \u00e9 crucial. Precisamos ter controle do jogo e estamos prontos para isso. Passamos por algumas dificuldades no ano passado, mas mostramos que temos a mentalidade forte. O jogo ser\u00e1 dif\u00edcil porque o Flamengo \u00e9 uma equipe muito boa.&#8221;, disse.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Final do Intercontinental:&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/flamengo-campeao-psg-retrospecto\/\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo j\u00e1 foi campe\u00e3o em cima do PSG; relembre<\/a><\/strong><\/li>\n\n\n\n<li><strong>Velho conhecido: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/arbitro-final-flamengo-psg-intercontinental\/\" target=\"_blank\" rel=\"noreferrer noopener\">Saiba o \u00e1rbitro da final entre Flamengo e PSG<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8220;S\u00e3o poucas oportunidades de disputar uma final dessa. Estamos cientes da import\u00e2ncia desse jogo. \u00c9 uma honra poder disputar a final da Copa Intercontinental. Representa muito para n\u00f3s e estamos felizes de estar aqui.&#8221;, falou o espanhol.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Marquinhos joga a final contra o Flamengo?<\/h2>\n\n\n\n<p>O zagueiro Marquinhos \u00e9 d\u00favida para a final contra o Flamengo, <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/psg-relacionados-flamengo\/\" target=\"_blank\" rel=\"noreferrer noopener\">apesar de ter sido relacionado<\/a><\/strong>. O defensor brasileiro sofreu uma&nbsp;<strong>pancada no tornozelo esquerdo<\/strong>&nbsp;durante o primeiro tempo contra o Athletic Bilbao, pela Champions League, e foi desfalque no <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/como-foi-psg-antes-final-flamengo\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00faltimo compromisso do PSG<\/a><\/strong> no Campeonato Franc\u00eas.<\/p>\n\n\n\n<p>O t\u00e9cnico Luis Enrique n\u00e3o deu muitos detalhes sobre a situa\u00e7\u00e3o do atleta, mas foi direto sobre o assunto: &#8220;Teremos mais um treino nesta ter\u00e7a, mas Marquinhos est\u00e1 pronto. Vamos ver o estado dele ap\u00f3s o treinamento e vamos decidir amanh\u00e3 se ele come\u00e7a como titular ou n\u00e3o.&#8221;.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>PSG x Flamengo: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/psg-flamengo-horario-escalacoes-onde-assistir\/\" target=\"_blank\" rel=\"noreferrer noopener\">Saiba tudo sobre a final do Intercontinental<\/a><\/strong><\/li>\n\n\n\n<li><strong>Ele fica: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/jose-boto-renovacao-flamengo\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jos\u00e9 Boto confirma renova\u00e7\u00e3o com o Flamengo<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Um desfalque de peso confirmado \u00e9 o lateral-direito <strong>Achraf Hakimi<\/strong>, que&nbsp;se recupera de uma&nbsp;<strong>grave les\u00e3o no tornozelo esquerdo<\/strong>&nbsp;e&nbsp;<strong>n\u00e3o jogar\u00e1<\/strong>&nbsp;contra o&nbsp;<strong>Flamengo<\/strong>. &#8220;Hakimi n\u00e3o est\u00e1 recuperado e n\u00e3o vai jogar amanh\u00e3.&#8221;, afirmou o treinador.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir ao vivo a PSG x Flamengo<\/h2>\n\n\n\n<p>A partida entre PSG x Flamengo ter\u00e1 transmiss\u00e3o do SporTV, Globo, GE TV e Caz\u00e9TV. O&nbsp;<strong>365Scores<\/strong>&nbsp;tamb\u00e9m far\u00e1 a cobertura em tempo real,&nbsp;al\u00e9m de disponibilizar onde assistir aos&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\">j<strong>ogos de hoje na TV.<\/strong><\/a><\/p>\n\n\n\n<div\n\ndata-scores-container-id=\"widgets-samples\"\n\ndata-widget-type=\"predictions\"\n\ndata-entity-type=\"game\"\n\ndata-show-powered-by=\"true\"\n\ndata-publisher-id=\"2\"\n\ndata-user-country-id=\"21\"\n\ndata-entity-id=\"4630907\"\n\ndata-show-odds=\"true\"\n\ndata-show-sponsorship=\"true\"\n\ndata-enable-impression-count=\"true\"\n\ndata-allow-insight=\"true\"\n\ndata-lang=\"pt-BR\">\n\n<\/div>\n\n<script\n\nsrc=\"https:\/\/widgets.365scores.com\/main.js\">\n\n<\/script>\n\n\n\n<p><strong><em>N\u00e3o quer perder nenhum&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>placar de futebol<\/em><\/strong><\/a><strong><em>&nbsp;ou os&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de hoje na tv<\/em><\/strong><\/a><strong><em>? Fique por dentro acessando o site do 365Scores: resultado ao vivo,&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flamengo e PSG se enfrentam nesta quarta-feira (17), \u00e0s 14h (de Bras\u00edlia), no Catar, pela final da Copa Intercontinental de Clubes. O t\u00e9cnico Luis Enrique concedeu entrevista coletiva e falou sobre o confronto entre as equipes. Ansioso pelo embate com o representante brasileiro no Mundial, o treinador espanhol elogiou a equipe carioca, principalmente pelo estilo &hellip;<\/p>\n","protected":false},"author":57,"featured_media":263543,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1738,1114],"tags":[71,183,3617,1735,5],"content-tags":[1436,1346],"class_list":["post-263534","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intercontinental-clubes","category-futebol-internacional","tag-flamengo","tag-futebol-internacional","tag-intercontinental","tag-luis-enrique","tag-psg","content-tags-game-news","content-tags-general-news","article_type-news","entity_type-competitor","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/263534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=263534"}],"version-history":[{"count":3,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/263534\/revisions"}],"predecessor-version":[{"id":263560,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/263534\/revisions\/263560"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/263543"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=263534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=263534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=263534"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=263534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}