{"id":261570,"date":"2025-12-09T19:03:06","date_gmt":"2025-12-09T22:03:06","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=261570"},"modified":"2025-12-09T19:03:10","modified_gmt":"2025-12-09T22:03:10","slug":"champions-league-barcelona-frankfurt-novo-camp-nou-kounde","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/champions-league-barcelona-frankfurt-novo-camp-nou-kounde\/","title":{"rendered":"Barcelona vence de virada na Champions com show de Kound\u00e9 no novo Camp Nou"},"content":{"rendered":"\n<p>Foi apertado, mas o <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/fc-barcelona-132\" target=\"_blank\" rel=\"noreferrer noopener\">Barcelona<\/a> conseguiu sua primeira vit\u00f3ria na <strong>Champions League<\/strong> no novo Camp Nou. Com dois gols do zagueiro <strong>Jules Kound\u00e9<\/strong>, os <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/uefa-champions-league-572\/eintracht-frankfurt-fc-barcelona-132-337-572#id=4538473\" target=\"_blank\" rel=\"noreferrer noopener\">Cul\u00e9s bateram o Eintracht Frankfurt<\/a>, de virada, por 2 a 1.<\/p>\n\n\n\n<p>A noite que marcou a volta do lend\u00e1rio Camp Nou ao cen\u00e1rio europeu tinha de tudo para ser especial, por\u00e9m, logo passou a ser um pesadelo. Aos 21 minutos, em belo contra-ataque puxado por Brown, <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/ansgar-knauff-79608\" target=\"_blank\" rel=\"noreferrer noopener\">Knauff<\/a> aproveitou para abrir o placar.<\/p>\n\n\n\n<p>Pouco criativo, o Barcelona tinha a posse, mas a noite que era pra ser m\u00e1gica, n\u00e3o vinha tendo brilho algum. Lamine Yamal, por exemplo, errou a maioria de suas tentativas. J\u00e1 Lewandowski e Raphinha pouco tocaram na bola. Coube, ent\u00e3o, <strong>a um zagueiro resolver a situa\u00e7\u00e3o.<\/strong><\/p>\n\n\n\n<p>Na volta do intervalo, <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/jules-kounde-55138\" target=\"_blank\" rel=\"noreferrer noopener\">Jules Kound\u00e9<\/a> se aventurou no campo de ataque em duas oportunidades \u2014 e fez valer cada uma delas. Foram dois cruzamentos na segunda trave do goleiro do Frankfurt. Primeiro dos p\u00e9s de Rashford e depois Lamine Yamal. Ambas foram de encontro ao zagueiro franc\u00eas, que fez dois gols parecidos de cabe\u00e7a.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">GOOOOOOOOOL! \ud83d\ude31\ud83d\ude31\ud83d\ude31 O HER\u00d3I IMPROV\u00c1VEL PRA SALVAR O BARCELONA! KOUND\u00c9 DE NOVO! \u00c9 A VIRADA CUL\u00c9 NO CAMP NOU! \ud83d\udd35\ud83d\udd34<br><br>\u26a0\ufe0f EXCLUSIVO! Barcelona x E. Frankfurt AO VIVO na <a href=\"https:\/\/twitter.com\/TNTbr?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@tntbr<\/a> e na <a href=\"https:\/\/twitter.com\/StreamMaxBR?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@streammaxbr<\/a> (<a href=\"https:\/\/t.co\/mmbf9LCqZq\">https:\/\/t.co\/mmbf9LCqZq<\/a>)! <a href=\"https:\/\/twitter.com\/hashtag\/CasaDaChampions?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#CasaDaChampions<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/HBOMax?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#HBOMax<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TR?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#TR<\/a> <a href=\"https:\/\/t.co\/9w3Fz7q9dW\">pic.twitter.com\/9w3Fz7q9dW<\/a><\/p>&mdash; TNT Sports BR (@TNTSportsBR) <a href=\"https:\/\/twitter.com\/TNTSportsBR\/status\/1998502838943498294?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 9, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>N\u00e3o \u00e9 a primeira vez em 2025 que Kound\u00e9 resolve um jogo para o Barcelona. Ainda na \u00faltima temporada, o franc\u00eas foi o respons\u00e1vel pelo <strong>gol do t\u00edtulo na Copa do Rei contra o Real Madrid<\/strong>. Nesta ter\u00e7a, ele marcou seus primeiros gols na atual edi\u00e7\u00e3o da Premier League.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Siga o 365Scores no Google News: <\/em><\/strong><a href=\"https:\/\/news.google.com\/publications\/CAAqKAgKIiJDQklTRXdnTWFnOEtEVE0yTlhOamIzSmxjeTVqYjIwb0FBUAE?hl=pt-PT&amp;gl=PT&amp;ceid=PT:pt-150\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>Fique por dentro das not\u00edcias mais quentes do esporte!<\/em><\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p>A vit\u00f3ria d\u00e1 um respiro ao Barcelona, que volta a vencer depois de perder por 3 a 0 para o Chelsea. Agora com 10 pontos, o clube catal\u00e3o vai para a 14\u00aa coloca\u00e7\u00e3o. Vale frisar que ainda ter\u00e3o outros jogos na quarta-feira (10).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Tabela da Champions League<\/h2>\n\n\n\n<div data-widget-type=\"entityStandings\" data-entity-type=\"league\" data-widget-id=\"0.2q4e92eb6pq\" data-lang=\"pt-BR\" data-entity-id=\"572\" data-user-country-id=\"21\" data-publisher-id=\"2\" data-hide-powered-by=\"true\"><\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\"><\/script>\n\n\n\n<p><strong><em>N\u00e3o quer perder nenhum <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>placar de futebol<\/em><\/strong><\/a><strong><em> ou os <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de hoje na tv<\/em><\/strong><\/a><strong><em>? Fique por dentro acessando o site do 365Scores: resultado ao vivo, <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi apertado, mas o Barcelona conseguiu sua primeira vit\u00f3ria na Champions League no novo Camp Nou. Com dois gols do zagueiro Jules Kound\u00e9, os Cul\u00e9s bateram o Eintracht Frankfurt, de virada, por 2 a 1. A noite que marcou a volta do lend\u00e1rio Camp Nou ao cen\u00e1rio europeu tinha de tudo para ser especial, por\u00e9m, &hellip;<\/p>\n","protected":false},"author":25,"featured_media":261571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1114,1133],"tags":[1376,478],"content-tags":[1436,1346],"class_list":["post-261570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol-internacional","category-liga-dos-campeoes","tag-barcelona","tag-eintracht-frankfurt","content-tags-game-news","content-tags-general-news","article_type-news","entity_type-competition","entity_type-match","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/261570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=261570"}],"version-history":[{"count":2,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/261570\/revisions"}],"predecessor-version":[{"id":261574,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/261570\/revisions\/261574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/261571"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=261570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=261570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=261570"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=261570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}