{"id":260027,"date":"2025-12-05T10:41:03","date_gmt":"2025-12-05T13:41:03","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=260027"},"modified":"2025-12-05T10:41:06","modified_gmt":"2025-12-05T13:41:06","slug":"leonardo-jardim-cruzeiro-santos","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/leonardo-jardim-cruzeiro-santos\/","title":{"rendered":"De olho na Copa do Brasil: Cruzeiro deve enfrentar o Santos com reservas"},"content":{"rendered":"\n<p>\u00c0s v\u00e9speras dos duelos da semifinal pela <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/copa-do-brasil-115\" target=\"_blank\" rel=\"noreferrer noopener\">Copa do Brasil<\/a><\/strong>, o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/cruzeiro-1213\" target=\"_blank\" rel=\"noreferrer noopener\">Cruzeiro <\/a><\/strong>deve <strong>poupar seus titulares<\/strong> do jogo da \u00faltima rodada do <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/brasileirao-serie-a-113\" target=\"_blank\" rel=\"noreferrer noopener\">Campeonato Brasileiro<\/a><\/strong> contra o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/santos-1224\" target=\"_blank\" rel=\"noreferrer noopener\">Santos<\/a><\/strong>. As equipes se enfrentam neste domingo (7), \u00e0s 16h (de Bras\u00edlia), na Vila Belmiro.<\/p>\n\n\n\n<p>A <strong>Raposa enfrentar\u00e1 o Corinthians<\/strong> nos dias 10 e 14 de dezembro, poucos dias depois de pegar o Peixe. Diante disso, o t\u00e9cnico Leonardo Jardim indicou que deve fazer a rodagem do elenco &#8211; contra sua vontade &#8211; e dar\u00e1 minutos a atletas que t\u00eam tido menos oportunidades.<\/p>\n\n\n\n<p>&#8220;Para n\u00f3s com certeza nos custaria jogar na nossa melhor vers\u00e3o. Voc\u00ea sabe que n\u00e3o sou apologista de rodar o plantel e fazer grandes trocas, de v\u00e1rios jogadores. Mas o calend\u00e1rio exige, temos um jogo daqui a seis dias e eu n\u00e3o posso colocar o grupo que jogou mais, que j\u00e1 traz 50,60 jogos, fazer viagens, jogar mais um jogo dif\u00edcil.&#8221;, afirmou o treinador portugu\u00eas, em entrevista coletiva.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Problemas no Tim\u00e3o: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/garro-lesao-yuri-alberto-corinthians\/\" target=\"_blank\" rel=\"noreferrer noopener\">Garro e Yuri t\u00eam problemas musculares<\/a><\/strong><\/li>\n\n\n\n<li><strong>Vasco x Fluminense: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/lucas-piton-lesao-ligamento-vasco-semifinal-copa-do-brasil\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lucas Piton sofre les\u00e3o no ligamento e preocupa<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>&#8220;\u00c9 uma porta que se abre para aqueles que t\u00eam jogado menos, mostrar por que est\u00e3o aqui no elenco do Cruzeiro e tamb\u00e9m ganhar algum ritmo. N\u00e3o vamos jogar s\u00f3 com 11, vamos jogar com outros, e esses tamb\u00e9m v\u00e3o ganhar um pouco de atividade, de tempo de jogo, para nos ajudarem nas semifinais.&#8221;, completou.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cruzeiro n\u00e3o briga por nada no Brasileir\u00e3o<\/h2>\n\n\n\n<p>Com o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/cruzeiro-empate-botafogo-brasileirao\/\" target=\"_blank\" rel=\"noreferrer noopener\">empate diante do Botafogo em 2 a 2<\/a><\/strong>, o Cruzeiro n\u00e3o tem mais objetivos no Campeonato Brasileiro ap\u00f3s j\u00e1 ter conquistado a vaga direta na Libertadores de 2026. O trope\u00e7o no Mineir\u00e3o fez o time celeste chegar aos 70 pontos na terceira coloca\u00e7\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">Os gols marcados por Christian e Matheus Pereira contra o Botafogo. \ud83e\udd8a\u26bd\ufe0f <a href=\"https:\/\/t.co\/st0ClJa5gm\">pic.twitter.com\/st0ClJa5gm<\/a><\/p>&mdash; Cruzeiro \ud83e\udd8a (@Cruzeiro) <a href=\"https:\/\/twitter.com\/Cruzeiro\/status\/1996746928197894550?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">December 5, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p>Diante disso, o Cabuloso n\u00e3o pode mais ser ultrapassado pelo Mirassol, que est\u00e1 em quarto e soma 66 pontos. Ainda, os mineiros n\u00e3o podem mais alcan\u00e7ar o vice-l\u00edder Palmeiras, que tem tr\u00eas pontos a mais, mas contam com tr\u00eas vit\u00f3rias de vantagem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Santos perto de se livrar do rebaixamento<\/h2>\n\n\n\n<p>A fala de Leonardo Jardim \u00e9 uma <strong>boa not\u00edcia para o Santos<\/strong>, que est\u00e1 muito perto de se livrar do rebaixamento no Brasileir\u00e3o. Dependendo apenas de si para cumprir esse objetivo, o time paulista deve enfrentar, portanto, uma equipe muito desfalcada.<\/p>\n\n\n\n<p>Atual <strong>14\u00ba colocado com 44 pontos<\/strong>, o Peixe precisa de um empate para chegar ao m\u00e1gico n\u00famero de 45 pontos, mas uma vit\u00f3ria contra o Cruzeiro elimina qualquer possibilidade de queda para a S\u00e9rie B.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira as datas, hor\u00e1rios e onde assistir \u00e0s semifinais da Copa do Brasil<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cruzeiro x Corinthians \u2013 10\/12, \u00e0s 21h30 \u2013 Globo, Sportv, Premiere e Prime Video<\/li>\n\n\n\n<li>Vasco x Fluminense \u2013 11\/12, \u00e0s 20h \u2013 Sportv, Premiere e Prime Video<\/li>\n\n\n\n<li>Corinthians x Cruzeiro \u2013 14\/12, \u00e0s 18h \u2013 Globo, Sportv, Premiere e Prime Video<\/li>\n\n\n\n<li>Fluminense x Vasco \u2013 14\/12, \u00e0s 20h30 \u2013 Sportv, Premiere e Prime Video<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Quando ser\u00e1 a final da Copa do Brasil?<\/h2>\n\n\n\n<p>A  CBF indica que os jogos de ida e volta devem ser\u00a0<strong>disputados nos dias 17 e 21 de dezembro<\/strong>, encerrando a temporada no Brasil.<\/p>\n\n\n\n<p><em><strong>Fique por dentro de&nbsp;<\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>tudo do futebol do Brasil e do mundo<\/em><\/strong><\/a><em><strong>&nbsp;acessando o site do 365scores: resultado ao vivo,&nbsp;<\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><em><strong>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0s v\u00e9speras dos duelos da semifinal pela Copa do Brasil, o Cruzeiro deve poupar seus titulares do jogo da \u00faltima rodada do Campeonato Brasileiro contra o Santos. As equipes se enfrentam neste domingo (7), \u00e0s 16h (de Bras\u00edlia), na Vila Belmiro. A Raposa enfrentar\u00e1 o Corinthians nos dias 10 e 14 de dezembro, poucos dias &hellip;<\/p>\n","protected":false},"author":57,"featured_media":260032,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1129,7],"tags":[1375,937,59,166,129],"content-tags":[1346,1433],"class_list":["post-260027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-copa-do-brasil","category-futebol","tag-brasileirao","tag-copa-do-brasil","tag-cruzeiro","tag-futebol-brasileiro","tag-santos","content-tags-general-news","content-tags-team-news","article_type-news","entity_type-competitor","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/260027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=260027"}],"version-history":[{"count":2,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/260027\/revisions"}],"predecessor-version":[{"id":260035,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/260027\/revisions\/260035"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/260032"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=260027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=260027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=260027"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=260027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}