{"id":252367,"date":"2025-11-11T14:05:54","date_gmt":"2025-11-11T17:05:54","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=252367"},"modified":"2025-11-11T14:15:46","modified_gmt":"2025-11-11T17:15:46","slug":"real-madrid-lyon-contratacao-endrick","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/real-madrid-lyon-contratacao-endrick\/","title":{"rendered":"Real Madrid libera, e Lyon encaminha contrata\u00e7\u00e3o de Endrick"},"content":{"rendered":"\n<p>O futuro de <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/endrick-106075\" target=\"_blank\" rel=\"noreferrer noopener\">Endrick <\/a><\/strong>est\u00e1 muito perto de estar decidido. O <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/real-madrid-131\" target=\"_blank\" rel=\"noreferrer noopener\">Real Madrid<\/a><\/strong> deu o &#8220;ok&#8221; nas conversas e o <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/lyon-465\" target=\"_blank\" rel=\"noreferrer noopener\">Lyon <\/a><\/strong>encaminhou de vez a contrata\u00e7\u00e3o do centroavante brasileiro por <strong>empr\u00e9stimo<\/strong>.<\/p>\n\n\n\n<p>Diante disso, as quest\u00f5es burocr\u00e1ticas entre as partes j\u00e1 est\u00e3o sendo resolvidas para que o neg\u00f3cio seja conclu\u00eddo. O atleta de 19 anos jogar\u00e1 pelo time franc\u00eas <strong>de janeiro (na abertura da janela) at\u00e9 julho do ano que vem<\/strong>, at\u00e9 o encerramento da temporada 2025\/26. As informa\u00e7\u00f5es s\u00e3o do &#8220;ge&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"817\" height=\"1024\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/11\/endrick-lyon-817x1024.jpg\" alt=\"\" class=\"wp-image-252382\" style=\"width:400px;height:auto\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/11\/endrick-lyon-817x1024.jpg 817w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/11\/endrick-lyon-239x300.jpg 239w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/11\/endrick-lyon-768x963.jpg 768w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/11\/endrick-lyon.jpg 1021w\" sizes=\"auto, (max-width: 817px) 100vw, 817px\" \/><figcaption class=\"wp-element-caption\">Montagem de Endrick com a camisa do Lyon. Foto: 365Scores<\/figcaption><\/figure>\n\n\n\n<p><strong>Endrick se mostrou disposto<\/strong> a refor\u00e7ar o Lyon desde os primeiros contatos do clube da Fran\u00e7a com o Real Madrid e seu estafe. Em busca de mais minutos em campo, o centroavante tamb\u00e9m deseja estar em evid\u00eancia visando uma poss\u00edvel convoca\u00e7\u00e3o para a <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/fifa-world-cup-5930\" target=\"_blank\" rel=\"noreferrer noopener\">Copa do Mundo de 2026<\/a><\/strong>.<\/p>\n\n\n\n<p>Recentemente, o t\u00e9cnico <strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/ancelotti-conversa-endrick-convocacao-copa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Carlo Ancelotti revelou que acompanha a situa\u00e7\u00e3o de Endrick<\/a><\/strong> no Real e que n\u00e3o descarta uma eventual presen\u00e7a na lista para o Mundial. No entanto, fez ressalvas quanto a isso e apontou o caminho para o jovem jogador alcan\u00e7ar seus objetivos.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u201cMuito importante para n\u00f3s\u201d: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/casemiro-selecao-neymar\/\" target=\"_blank\" rel=\"noreferrer noopener\">Casemiro afirma que Sele\u00e7\u00e3o precisa de Neymar<\/a><\/strong><\/li>\n\n\n\n<li><strong>Conhe\u00e7a: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/clube-36-mil-quilometros-copa-da-franca\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clube viaja 36 mil quil\u00f4metros para partida da Copa da Fran\u00e7a<\/a><\/strong><\/li>\n<\/ul>\n\n\n\n<p>Apesar de enfim ter estreado na temporada 2025\/26 no dia 1\u00ba de novembro, Endrick n\u00e3o entrou mais em campo pelo Real Madrid desde ent\u00e3o. Diante do Valencia, o centroavante brasileiro&nbsp;<strong>atuou por 12 minutos<\/strong>&nbsp;no segundo tempo. A partir da\u00ed, n\u00e3o saiu do banco de reservas nos dois compromissos seguintes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">N\u00fameros de Endrick na \u00faltima temporada<\/h2>\n\n\n\n<p>Apesar dos altos e baixos, Endrick teve&nbsp;<strong>bons n\u00fameros em 2024\/25<\/strong>, sua primeira temporada como jogador do Real Madrid. O brasileiro foi o artilheiro da equipe na Copa do Rei, mas n\u00e3o conseguiu ter a mesma regularidade em suas atua\u00e7\u00f5es nas outras competi\u00e7\u00f5es.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>37 jogos<strong>&nbsp;<\/strong>(8 como titular)<\/li>\n\n\n\n<li>7 gols<\/li>\n\n\n\n<li>0 assist\u00eancias<\/li>\n<\/ul>\n\n\n\n<p><strong><em>N\u00e3o quer perder nada sobre o Mercado da Bola do futebol brasileiro? Acesse o 365Scores para saber as contrata\u00e7\u00f5es e&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/brasileirao-serie-a-113\/transfers\" target=\"_blank\" rel=\"noreferrer noopener\">transfer\u00eancias de hoje<\/a>&nbsp;dos times!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O futuro de Endrick est\u00e1 muito perto de estar decidido. O Real Madrid deu o &#8220;ok&#8221; nas conversas e o Lyon encaminhou de vez a contrata\u00e7\u00e3o do centroavante brasileiro por empr\u00e9stimo. Diante disso, as quest\u00f5es burocr\u00e1ticas entre as partes j\u00e1 est\u00e3o sendo resolvidas para que o neg\u00f3cio seja conclu\u00eddo. O atleta de 19 anos jogar\u00e1 &hellip;<\/p>\n","protected":false},"author":57,"featured_media":246174,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1116],"tags":[1330,241,21,9],"content-tags":[1347],"class_list":["post-252367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-da-bola","tag-endrick","tag-lyon","tag-mercado-da-bola","tag-real-madrid","content-tags-transfer-rumors","article_type-news","entity_type-athlete","entity_type-competitor","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/252367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=252367"}],"version-history":[{"count":3,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/252367\/revisions"}],"predecessor-version":[{"id":252383,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/252367\/revisions\/252383"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/246174"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=252367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=252367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=252367"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=252367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}