{"id":247077,"date":"2025-10-29T08:44:52","date_gmt":"2025-10-29T11:44:52","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=247077"},"modified":"2025-10-29T08:44:55","modified_gmt":"2025-10-29T11:44:55","slug":"entrevista-diego-hernandez-remo-botafogo","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/entrevista-diego-hernandez-remo-botafogo\/","title":{"rendered":"Emprestado pelo Botafogo, Diego Hern\u00e1ndez celebra grande fase no Remo e mira t\u00edtulo da S\u00e9rie B"},"content":{"rendered":"\n<p>O <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/remo-7383\" target=\"_blank\" rel=\"noreferrer noopener\">Remo<\/a> est\u00e1 em ascens\u00e3o na <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/brasileirao---serie-b-superbet-116\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e9rie B do Campeonato Brasileiro,<\/a> com <strong>seis vit\u00f3rias consecutivas<\/strong>. Se antes houve d\u00favida quanto ao acesso, hoje o Le\u00e3o Azul \u00e9 <strong>postulante ao t\u00edtulo<\/strong>. A equipe ocupa a vice-lideran\u00e7a com 57 pontos, tr\u00eas a menos do Coritiba, e, segundo c\u00e1lculos do\u00a0Departamento de Matem\u00e1tica da Universidade Federal de Minas Gerais (MG), <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/serie-b-chances-acesso-queda-34-rodada\/\" target=\"_blank\" rel=\"noreferrer noopener\">tem 69,6% de chances de subir \u00e0 S\u00e9rie A<\/a>.<\/p>\n\n\n\n<p>O crescimento do clube paraense veio junto ao \u00f3timo momento do atacante <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/diego-hernandez-81716\" target=\"_blank\" rel=\"noreferrer noopener\">Diego Hern\u00e1ndez<\/a>. O uruguaio soma <strong>tr\u00eas gols<\/strong> e <strong>duas assist\u00eancias<\/strong> nos \u00faltimos seis jogos. Em <strong>entrevista exclusiva ao 365Scores<\/strong>, o jogador celebrou esse per\u00edodo vitorioso e mirou o t\u00edtulo da S\u00e9rie B:<\/p>\n\n\n\n<p id=\"tw-target-text\">&#8220;\u00c9 um \u00f3timo momento na minha carreira. Me sinto muito bem e ansioso para alcan\u00e7ar meus objetivos. O fator chave (pela arrancada) \u00e9 o trabalho que fazemos dia a dia, estamos trabalhando muito duro para fechar o ano da melhor maneira&#8221;.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Exclusiva 365Scores: <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/entrevista-jp-avai-vasco\/\" target=\"_blank\" rel=\"noreferrer noopener\">Emprestado pelo Vasco, JP acredita no acesso do Ava\u00ed \u00e0 S\u00e9rie A<\/a><\/strong><\/li>\n\n\n\n<li><strong>Mais de 600 est\u00e1dios em 54 pa\u00edses: <\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/estadios-paises-mochileiro-da-bola-brasileiro-futebol\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>conhe\u00e7a o brasileiro que viaja pelo mundo acompanhando futebol<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p id=\"tw-target-text\">&#8220;Queremos o acesso e o trof\u00e9u sem sombra de d\u00favidas. Sabemos o qu\u00e3o dif\u00edcil \u00e9 o Campeonato Brasileiro, vamos passo a passo&#8221;, completou ao 365Scores.<\/p>\n\n\n\n<p>Diego Hern\u00e1ndez chegou ao Remo em julho emprestado pelo Botafogo <strong>at\u00e9 o fim da temporada<\/strong>. O respons\u00e1vel pela contrata\u00e7\u00e3o foi <strong>Marcos Braz<\/strong>, diretor executivo de futebol do clube paraense. O atacante rasgou elogios ao dirigente multicampe\u00e3o pelo Flamengo.<\/p>\n\n\n\n<p id=\"tw-target-text\">&#8220;D\u00e1 para ver o talento do Marcos (Braz) para comandar e liderar um clube a grandes feitos. O que estou dizendo n\u00e3o \u00e9 novidade, basta olhar para a passagem dele pelo Flamengo.&#8221;<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\u26bd\ufe0f\ud83e\udd81 DIEGO HERN\u00c1NDEZ <a href=\"https:\/\/twitter.com\/hashtag\/OReiDaAmaz%C3%B4nia?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#OReiDaAmaz\u00f4nia<\/a> <a href=\"https:\/\/t.co\/1eLShplxx2\">pic.twitter.com\/1eLShplxx2<\/a><\/p>&mdash; Clube do Remo (@ClubeDoRemo) <a href=\"https:\/\/twitter.com\/ClubeDoRemo\/status\/1979751939463348294?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">October 19, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Diego Hern\u00e1ndez vai voltar ao Botafogo? Veja o que ele disse ao 365Scores<\/h2>\n\n\n\n<p>O contrato de Diego Hern\u00e1ndez com o Botafogo \u00e9 <strong>v\u00e1lido at\u00e9 o fim de 2026<\/strong>. Questionado sobre o futuro, o uruguaio n\u00e3o garantiu se permanecer\u00e1 no Remo ou se voltar\u00e1 ao Alvinegro, mas deixou claro estar <strong>&#8220;muito feliz&#8221; <\/strong>no clube paraense.<\/p>\n\n\n\n<p id=\"tw-target-text\">&#8220;Hoje estou totalmente focado no Remo. Quero alcan\u00e7ar meus objetivos e fazer hist\u00f3ria. O resto veremos. Hoje estou muito feliz com o clube e as pessoas ao redor dele&#8221;.<\/p>\n\n\n\n<p>Antes de ir ao Remo, o atacante foi emprestado ao <strong>Le\u00f3n<\/strong>, do M\u00e9xico, e ao <strong>Everton<\/strong>, do Chile. Ele afirmou ter gostado da experi\u00eancia no futebol mexicano, por\u00e9m viu como <strong>&#8220;perda de tempo&#8221;<\/strong> a passagem no time chileno.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Ex-Vasco e Atl\u00e9tico-MG: <\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/entrevista-fabio-gomes-mexico-atletico-mg-vasco\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>F\u00e1bio Gomes evolui no M\u00e9xico e projeta retorno ao Brasil<\/strong><\/a><\/li>\n\n\n\n<li><strong>Ex-Botafogo, Inter e Vasco: <\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/entrevista-paulo-victor-botafogo-vasco-inter\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Paulo Victor comemora boa fase no futebol de Portugal<\/strong><\/a><\/li>\n<\/ul>\n\n\n\n<p id=\"tw-target-text\">&#8220;A verdade \u00e9 que o M\u00e9xico foi muito bom para mim e eu gostei muito. Prefiro n\u00e3o falar do Chile, foi perda de tempo. Eu vinha de problemas familiares, e o time tamb\u00e9m n\u00e3o foi bem.&#8221;<\/p>\n\n\n\n<p>Diego Hern\u00e1ndez est\u00e1 no Botafogo desde 2023 e <strong>participou do elenco campe\u00e3o<\/strong> da Libertadores e do Brasileir\u00e3o em 2024. O jogador disputou tr\u00eas partidas na competi\u00e7\u00e3o sul-americana e dez no campeonato nacional.<\/p>\n\n\n\n<p id=\"tw-target-text\">&#8220;Fui campe\u00e3o e <strong>n\u00e3o recebi a medalha<\/strong>, mas joguei e isso me deixa feliz. Ter um trof\u00e9u t\u00e3o grande na vitrine me enche de orgulho&#8221;, sobre o t\u00edtulo da Libertadores.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">N\u00fameros de Diego Hern\u00e1ndez no Remo:<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Jogos: 12<\/li>\n\n\n\n<li>Gols: 3<\/li>\n\n\n\n<li>Assist\u00eancias: 2<\/li>\n\n\n\n<li>Chutes: 16<\/li>\n\n\n\n<li>Chutes no gol: 9<\/li>\n\n\n\n<li>Minutos jogados: 639<\/li>\n\n\n\n<li>Nota m\u00e9dia 365Scores: 7<\/li>\n<\/ul>\n\n\n\n<p><strong><em>Quer saber onde assistir aos <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de futebol hoje na TV<\/em><\/strong><\/a><strong><em>? Fique por dentro acessando o site do 365scores: resultado ao vivo, <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em> e muito mais!<\/em><\/strong><\/p>\n\n\n\n<div\n    data-scores-container-id=\"widgets-samples\"\n    data-widget-type=\"predictions\"\n    data-entity-type=\"team\"\n    data-show-powered-by=\"true\"\n    data-publisher-id=\"2\"\n    data-user-country-id=\"21\"\n    data-entity-id=\"7383\"\n    data-show-odds=\"true\"\n    data-show-sponsorship=\"true\"\n    data-enable-impression-count=\"true\"\n    data-allow-insight=\"true\"\n    data-lang=\"pt-BR\">\n<\/div>\n<script\n    src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>O Remo est\u00e1 em ascens\u00e3o na S\u00e9rie B do Campeonato Brasileiro, com seis vit\u00f3rias consecutivas. Se antes houve d\u00favida quanto ao acesso, hoje o Le\u00e3o Azul \u00e9 postulante ao t\u00edtulo. A equipe ocupa a vice-lideran\u00e7a com 57 pontos, tr\u00eas a menos do Coritiba, e, segundo c\u00e1lculos do\u00a0Departamento de Matem\u00e1tica da Universidade Federal de Minas Gerais &hellip;<\/p>\n","protected":false},"author":51,"featured_media":247079,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1126],"tags":[1342,1558],"content-tags":[1355,1356],"class_list":["post-247077","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-b","tag-botafogo","tag-remo","content-tags-exclusive","content-tags-interview","article_type-exclusive-interview","entity_type-athlete","entity_type-competitor","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/247077","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/51"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=247077"}],"version-history":[{"count":4,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/247077\/revisions"}],"predecessor-version":[{"id":248130,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/247077\/revisions\/248130"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/247079"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=247077"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=247077"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=247077"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=247077"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}