{"id":233426,"date":"2025-09-07T10:05:41","date_gmt":"2025-09-07T13:05:41","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=233426"},"modified":"2025-09-07T10:05:43","modified_gmt":"2025-09-07T13:05:43","slug":"piccini-aposentadoria-32-anos","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/piccini-aposentadoria-32-anos\/","title":{"rendered":"Ex-sele\u00e7\u00e3o italiana anuncia aposentadoria do futebol aos 32 anos"},"content":{"rendered":"\n<p>Ex-<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/italy-2375\" data-type=\"link\" data-id=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/italy-2375\" target=\"_blank\" rel=\"noreferrer noopener\">sele\u00e7\u00e3o italiana<\/a>, o lateral-direito<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/cristiano-piccini-6179\" data-type=\"link\" data-id=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/cristiano-piccini-6179\" target=\"_blank\" rel=\"noreferrer noopener\"> Cristiano Piccini<\/a> anunciou sua aposentadoria do futebol aos 32 anos. O \u00faltimo clube que o defensor defendeu foi o Yverdon, da Su\u00ed\u00e7a.<\/p>\n\n\n\n<p>Piccini se aposenta do futebol em meio a um in\u00edcio promissor e um fim melanc\u00f3lico. O italiano sofreu com les\u00f5es que o impediram de performar em alto n\u00edvel na reta final da temporada.<\/p>\n\n\n\n<p>O an\u00fancio da aposentadoria foi feito pelo pr\u00f3prio jogador. Piccini publicou uma mensagem para ele mesmo quando crian\u00e7a, afirmando que, apesar das realiza\u00e7\u00f5es pessoais, ele conviveria com les\u00f5es, solid\u00e3o e depress\u00e3o.<\/p>\n\n\n\n<p>&#8220;Voc\u00ea vestiu camisas que s\u00f3 via na TV quando era crian\u00e7a. Voc\u00ea viajou pelo mundo. Voc\u00ea aprendeu cinco l\u00ednguas. Viveu numa cidade que nem conseguias pronunciar. E sim, voc\u00ea realizou seu maior sonho, vestir a camisa da Sele\u00e7\u00e3o&#8221;, diz parte do texto de Piccini.<\/p>\n\n\n\n<p>&#8220;Mas nem tudo foi gl\u00f3ria. Havia o lado que n\u00e3o te contaram. O que voc\u00ea n\u00e3o v\u00ea nos sonhos de uma crian\u00e7a. Voc\u00ea vai quebrar. Literalmente. Seu joelho direito vai te apresentar ao inferno. Voc\u00ea estar\u00e1 a um passo de desistir de tudo. Ver\u00e1 colegas passarem por ti, os contratos desvanecerem, as portas se fechando&#8221;, complementou.<\/p>\n\n\n\n<p>Piccini, por\u00e9m, refletiu que, apesar das frustra\u00e7\u00f5es na carreira como jogador, \u00e9 muito realizado no \u00e2mbito pessoal e familiar.<\/p>\n\n\n\n<p>&#8220;Mas acima de tudo voc\u00ea vai aprender que a vida \u00e9 muito mais do que uma carreira. Voc\u00ea vai descobrir o verdadeiro amor. Voc\u00ea se tornar\u00e1 pai de duas crian\u00e7as que v\u00e3o olhar para voc\u00ea como voc\u00ea olhava para seus \u00eddolos. E voc\u00ea vai entender que a maior conquista n\u00e3o \u00e9 um trof\u00e9u, e sim chegar em casa a noite e ouvir isso, apesar de tudo, voc\u00ea \u00e9 o her\u00f3i deles&#8221;, concluiu.<\/p>\n\n\n\n<blockquote class=\"instagram-media\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DOTE11wjB5a\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\"><div style=\"padding:16px;\"> <a href=\"https:\/\/www.instagram.com\/p\/DOTE11wjB5a\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\" target=\"_blank\" rel=\"noopener\"> <div style=\" display: flex; flex-direction: row; align-items: center;\"> <div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div><\/div><\/div><div style=\"padding: 19% 0;\"><\/div> <div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewBox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div><div style=\"padding-top: 8px;\"> <div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">Ver esta publica\u00e7\u00e3o no Instagram<\/div><\/div><div style=\"padding: 12.5% 0;\"><\/div> <div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\"><div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div> <div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div> <div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div><\/div><div style=\"margin-left: 8px;\"> <div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div> <div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div><\/div><div style=\"margin-left: auto;\"> <div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div> <div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div> <div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div><\/div><\/div> <div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\"> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div> <div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div><\/div><\/a><p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a href=\"https:\/\/www.instagram.com\/p\/DOTE11wjB5a\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\" target=\"_blank\" rel=\"noopener\">Uma publica\u00e7\u00e3o partilhada por Cristiano Piccini (@crispiccini)<\/a><\/p><\/div><\/blockquote>\n<script async src=\"\/\/www.instagram.com\/embed.js\"><\/script>\n\n\n\n<h2 class=\"wp-block-heading\">Carreira de Piccini<\/h2>\n\n\n\n<p>Formado nas categorias de base da Fiorentina, Piccini foi tratado como um dos laterais-direitos mais promissores do futebol italiano, rendendo convoca\u00e7\u00f5es para as sele\u00e7\u00f5es de base do pa\u00eds. Por\u00e9m, n\u00e3o recebeu muitas chances na Viola, e, ap\u00f3s empr\u00e9stimos, foi vendido ao Betis em 2015.<\/p>\n\n\n\n<p>Piccini teve um bom desempenho no Betis, sendo o lateral-direito titular e marcando tr\u00eas gols em 2016\/17. No final daquela temporada, por\u00e9m, foi vendido ao Sporting, onde viveu sua melhor fase na carreira. <\/p>\n\n\n\n<p>Apesar de jogar por apenas uma temporada no clube portugu\u00eas, Piccini foi uma das refer\u00eancias defensivas da equipe, sendo titular em 39 dos 40 jogos que disputou. Seu desempenho no Sporting chamou a aten\u00e7\u00e3o do Valencia, que o comprou por oito milh\u00f5es de euros.<\/p>\n\n\n\n<p>Entretanto, apesar de uma boa primeira temporada no clube espanhol, foi l\u00e1 que Piccini come\u00e7ou a sofrer com problemas f\u00edsico. O italiano perdeu muitas partidas por les\u00e3o e foi vendido ao Estrela Vermelha em 2021\/22.<\/p>\n\n\n\n<p>Piccini ainda passou por Magdeburg, Sampdoria e Atl\u00e9tico San Luis antes de chegar ao Yverdon, da segunda divis\u00e3o su\u00ed\u00e7a. Em todos estes clubes, por\u00e9m, o lateral sofreu com les\u00f5es, e, ap\u00f3s jogar apenas cinco partidas em 2024\/25, anunciou sua aposentadoria do futebol.<\/p>\n\n\n\n<p><strong><em>N\u00e3o quer perder nenhum&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\"><strong><em>placar de futebol<\/em><\/strong><\/a><strong><em>&nbsp;ou os&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\"><strong><em>jogos de hoje na tv<\/em><\/strong><\/a><strong><em>? Fique por dentro acessando o site do 365Scores: resultado ao vivo,&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex-sele\u00e7\u00e3o italiana, o lateral-direito Cristiano Piccini anunciou sua aposentadoria do futebol aos 32 anos. O \u00faltimo clube que o defensor defendeu foi o Yverdon, da Su\u00ed\u00e7a. Piccini se aposenta do futebol em meio a um in\u00edcio promissor e um fim melanc\u00f3lico. O italiano sofreu com les\u00f5es que o impediram de performar em alto n\u00edvel na &hellip;<\/p>\n","protected":false},"author":54,"featured_media":233430,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1304,1115],"tags":[2773,2772],"content-tags":[1435,1346],"class_list":["post-233426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bastidores-da-bola-bastidores-da-bola","category-bastidores-da-bola","tag-aposentadoria","tag-piccini","content-tags-athlete-news","content-tags-general-news","article_type-news","entity_type-athlete","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/233426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=233426"}],"version-history":[{"count":5,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/233426\/revisions"}],"predecessor-version":[{"id":233436,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/233426\/revisions\/233436"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/233430"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=233426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=233426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=233426"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=233426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}