{"id":228949,"date":"2025-08-21T17:31:16","date_gmt":"2025-08-21T20:31:16","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=228949"},"modified":"2025-08-22T12:49:46","modified_gmt":"2025-08-22T15:49:46","slug":"al-nassr-x-al-ahli-horario-escalacoes-e-onde-assistir-ao-jogo-da-supercopa-saudita","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/al-nassr-x-al-ahli-horario-escalacoes-e-onde-assistir-ao-jogo-da-supercopa-saudita\/","title":{"rendered":"Al-Nassr x Al-Ahli: hor\u00e1rio, escala\u00e7\u00f5es e onde assistir ao jogo da Supercopa Saudita"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/al-nassr-fc-riyadh-7549\" target=\"_blank\" rel=\"noreferrer noopener\">Al-Nassr x Al-Ahli<\/a> se enfrentam neste s\u00e1bado (23), \u00e0s 9h (de Bras\u00edlia), em partida v\u00e1lida pela final da&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/super-cup-6164\" target=\"_blank\" rel=\"noreferrer noopener\">Supercopa Saudita<\/a>. O jogo acontece no Hong Kong Stadium, em Hong Kong.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Al-Nassr<\/h2>\n\n\n\n<p>Agora sob o comando de Jorge Jesus, o Al-Nassr vem remodelado para a temporada 2025\/26. Al\u00e9m do treinador portugu\u00eas, nomes badalados na Europa, como Jo\u00e3o F\u00e9lix, Kingsley Coman e I\u00f1igo Mart\u00ednez foram contratados para se juntar ao craque <strong>Cristiano Ronaldo<\/strong>.<\/p>\n\n\n\n<p>O resultado j\u00e1 foi mostrado no primeiro jogo, contra o Al-Ittihad, atual campe\u00e3o saudita. Mesmo com um jogador a menos, j\u00e1 que Man\u00e9 foi expulso, o Al-Nassr venceu por 2 a 1 e garantiu sua vaga na decis\u00e3o do pr\u00f3ximo s\u00e1bado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Al-Ahli<\/h2>\n\n\n\n<p>Agora sem Roberto Firmino, o Al-Ahli segue sendo um dos times mais s\u00f3lidos do futebol saudita. Prova disso foi a goleada aplicada no Al-Qisidiya, por 5 a 1, na semifinal da Supercopa. <\/p>\n\n\n\n<p>O time \u00e9 visto como o menos badalado entre aqueles que recebe investimento do PIF (Fundo de Investimento P\u00fablico), por\u00e9m, \u00e9 recheado de bons nomes, com destaque para Edouard Mendy, Ivan Toney e Riyad Mahrez.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escala\u00e7\u00f5es de Al-Nassr x Al-Ahli<\/h2>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do<\/strong>&nbsp;<strong>Al-Nassr<\/strong>: Bento, Yahya, I\u00f1igo Mart\u00ednez, Simakan e Boushal; Wesley, Brozovic, Alkhaibari e Coman; Jo\u00e3o F\u00e9lix e Cristiano Ronaldo.&nbsp;<strong>T\u00e9cnico<\/strong>: Jorge Jesus.<\/p>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do<\/strong>&nbsp;<strong>Al-Ahli<\/strong>: Mendy, Yaslam, Dams, Demiral e Mohammed Bakor; Aljohani, Kessi\u00e9, Alnabit, Mahrez e Al-Braikan; Toney&nbsp;<strong>T\u00e9cnico<\/strong>: Matthias Jaissle.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir a Al-Nassr x Al-Ahli<\/h2>\n\n\n\n<p>A partida entre Al-Nassr x Al-Ahli ter\u00e1 transmiss\u00e3o do BandSports, SporTV 2 e Canal GOAT. O&nbsp;<strong>365Scores<\/strong>&nbsp;tamb\u00e9m far\u00e1 a cobertura em tempo real,&nbsp;al\u00e9m de disponibilizar onde assistir aos&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\">jogos de hoje na TV.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha T\u00e9cnica \u2013 Al-Nassr x Al-Ahli<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data:<\/strong>&nbsp;23\/08\/2025<\/li>\n\n\n\n<li><strong>Hor\u00e1rio:<\/strong>&nbsp;9h (de Bras\u00edlia)<\/li>\n\n\n\n<li><strong>Local:<\/strong>&nbsp;Hong Kong Stadium, Hong Kong<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do<\/strong>\u00a0<strong>Al-Nassr<\/strong>: Bento, Yahya, I\u00f1igo Mart\u00ednez, Simakan e Boushal; Wesley, Brozovic, Alkhaibari e Coman; Jo\u00e3o F\u00e9lix e Cristiano Ronaldo.<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Al-Nassr<\/strong>: Jorge Jesus.<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do<\/strong>\u00a0<strong>Al-Ahli<\/strong>: Mendy, Yaslam, Dams, Demiral e Mohammed Bakor; Aljohani, Kessi\u00e9, Alnabit, Mahrez e Al-Braikan; Toney.<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Al-Ahli<\/strong>: Matthias Jaissle.<\/li>\n\n\n\n<li><strong>Onde assistir<\/strong>:<strong>&nbsp;365Scores<\/strong>, SporTV 2, BandSports e GOAT<\/li>\n<\/ul>\n\n\n\n<p><strong><em>Quer saber onde assistir aos&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de futebol hoje na TV<\/em><\/strong><\/a><strong><em>? Fique por dentro acessando o site do 365scores: resultado ao vivo,&nbsp;<\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em>&nbsp;e muito mais!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al-Nassr x Al-Ahli se enfrentam neste s\u00e1bado (23), \u00e0s 9h (de Bras\u00edlia), em partida v\u00e1lida pela final da&nbsp;Supercopa Saudita. O jogo acontece no Hong Kong Stadium, em Hong Kong. Como chega o Al-Nassr Agora sob o comando de Jorge Jesus, o Al-Nassr vem remodelado para a temporada 2025\/26. Al\u00e9m do treinador portugu\u00eas, nomes badalados na &hellip;<\/p>\n","protected":false},"author":25,"featured_media":228540,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1114,1201],"tags":[2152,1608],"content-tags":[1354],"class_list":["post-228949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol-internacional","category-campeonato-saudita","tag-al-ahli","tag-al-nassr","content-tags-where-to-watch","article_type-news","entity_type-competition","entity_type-match","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/228949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=228949"}],"version-history":[{"count":4,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/228949\/revisions"}],"predecessor-version":[{"id":229187,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/228949\/revisions\/229187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/228540"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=228949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=228949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=228949"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=228949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}