{"id":221144,"date":"2025-07-25T16:00:00","date_gmt":"2025-07-25T19:00:00","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=221144"},"modified":"2025-07-25T09:15:11","modified_gmt":"2025-07-25T12:15:11","slug":"caxias-x-ponte-preta-horario-escalacoes-e-onde-assistir-ao-jogo-da-14a-rodada-da-serie-c","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/caxias-x-ponte-preta-horario-escalacoes-e-onde-assistir-ao-jogo-da-14a-rodada-da-serie-c\/","title":{"rendered":"Caxias x Ponte Preta: hor\u00e1rio, escala\u00e7\u00f5es e onde assistir ao jogo da 14\u00aa rodada da S\u00e9rie C"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/serie-c-5518\/caxias-ponte-preta-1266-9083-5518#id=4392170\" target=\"_blank\" rel=\"noreferrer noopener\">Caxias x Ponte Preta<\/a> se enfrentam neste domingo (27), \u00e0s 16h30 (de Bras\u00edlia), pela\u00a014\u00aa rodada do Campeonato Brasileiro S\u00e9rie C. A partida ser\u00e1 disputada no Est\u00e1dio Centen\u00e1rio, em Caxias do Sul (RS).<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Caxias<\/h2>\n\n\n\n<p>O Caxias chega para a partida ap\u00f3s derrota para o N\u00e1utico por 2 a 0 pela rodada passada da S\u00e9rie C. L\u00edder com 27 pontos, o time ga\u00facho vem fazendo uma grande campanha na competi\u00e7\u00e3o, mas pode perder a ponta em caso de nova derrota neste domingo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega a Ponte Preta<\/h2>\n\n\n\n<p>A Ponte Preta chega para o duelo ap\u00f3s vencer o Floresta por 2 a 1 pela rodada passada da S\u00e9rie C. O time paulista vem fazendo grande campanha, ocupando a segunda coloca\u00e7\u00e3o com 26 pontos. A Macaca busca assumir a ponta nesta rodada, em caso de vit\u00f3ria sobre o l\u00edder.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escala\u00e7\u00f5es de Caxias x Ponte Preta<\/h2>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Caxias:&nbsp;<\/strong>Thiago Coelho; Thiago Ennes, Lucas Cunha, Alan, Marcelo Nunes; Vini Guedes, Mantuan, Tomas Bastos; Iago, Calyson e Eduardo Melo<\/p>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o da Ponte Preta:<\/strong> Diogo Silva; Jo\u00e3o Gabriel, Wanderson, Danrlei Santos, Artur; Lucas C\u00e2ndido, Emerson Santos, Elvis; Everton Brito, Tor\u00f3 e Jeh<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir a Caxias x Ponte Preta<\/h2>\n\n\n\n<p>A partida entre <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/serie-c-5518\/caxias-ponte-preta-1266-9083-5518#id=4392170\" target=\"_blank\" rel=\"noreferrer noopener\">Caxias x Ponte Preta<\/a>, pela rodada 14 do Campeonato Brasileiro S\u00e9rie C, ter\u00e1 transmiss\u00e3o do DAZN. O&nbsp;<strong>365Scores&nbsp;<\/strong>tamb\u00e9m far\u00e1 a cobertura em tempo real, al\u00e9m de disponibilizar&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\">onde assistir aos jogos na TV<\/a>.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha T\u00e9cnica Caxias x Ponte Preta<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data:<\/strong>&nbsp;27\/07\/2025<\/li>\n\n\n\n<li><strong>Hor\u00e1rio:<\/strong>&nbsp;16h<\/li>\n\n\n\n<li><strong>Local:<\/strong>\u00a0Est\u00e1dio Centen\u00e1rio (Caxias do Sul)<\/li>\n\n\n\n<li><strong>Rodada:&nbsp;<\/strong>14\u00aa<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Caxias:&nbsp;<\/strong>Thiago Coelho; Thiago Ennes, Lucas Cunha, Alan, Marcelo Nunes; Vini Guedes, Mantuan, Tomas Bastos; Iago, Calyson e Eduardo Melo<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Caxias:<\/strong> J\u00fanior Rocha<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o da Ponte Preta:<\/strong> Diogo Silva; Jo\u00e3o Gabriel, Wanderson, Danrlei Santos, Artur; Lucas C\u00e2ndido, Emerson Santos, Elvis; Everton Brito, Tor\u00f3 e Jeh<\/li>\n\n\n\n<li><strong>T\u00e9cnico da Ponte Preta<\/strong>: Alberto Valentim<\/li>\n\n\n\n<li><strong>Onde assistir<\/strong>: 365Scores e DAZN<\/li>\n<\/ul>\n\n\n\n<p><em>Para saber todos os&nbsp;<\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\"><strong><em>placares dos jogos de hoje ao vivo<\/em><\/strong><\/a><em>, entre no 365Scores! Fique por dentro dos hist\u00f3ricos dos confrontos, not\u00edcias, estat\u00edsticas, elencos e muito mais!<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Caxias x Ponte Preta se enfrentam neste domingo (27), \u00e0s 16h30 (de Bras\u00edlia), pela\u00a014\u00aa rodada do Campeonato Brasileiro S\u00e9rie C. A partida ser\u00e1 disputada no Est\u00e1dio Centen\u00e1rio, em Caxias do Sul (RS). Como chega o Caxias O Caxias chega para a partida ap\u00f3s derrota para o N\u00e1utico por 2 a 0 pela rodada passada da &hellip;<\/p>\n","protected":false},"author":49,"featured_media":221163,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1127],"tags":[1943,708,477],"content-tags":[1352],"class_list":["post-221144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-c","tag-campeonato-brasileiro-serie-c","tag-caxias","tag-ponte-preta","content-tags-game-preview","article_type-news","entity_type-match","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/221144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/49"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=221144"}],"version-history":[{"count":4,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/221144\/revisions"}],"predecessor-version":[{"id":221395,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/221144\/revisions\/221395"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/221163"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=221144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=221144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=221144"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=221144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}