{"id":217338,"date":"2025-06-18T09:33:47","date_gmt":"2025-06-18T12:33:47","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=217338"},"modified":"2025-06-18T09:33:54","modified_gmt":"2025-06-18T12:33:54","slug":"surfe-onde-assistir-saquarema","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/surfe-onde-assistir-saquarema\/","title":{"rendered":"Mundial de Surfe: onde assistir \u00e0 etapa de Saquarema"},"content":{"rendered":"\n<p>A nona etapa do\u00a0<strong>Circuito Mundial de Surfe<\/strong>\u00a0come\u00e7a no pr\u00f3ximo s\u00e1bado,\u00a0<strong>dia 21<\/strong>, na Praia de Ita\u00fana, em Saquarema. Dez brasileiros estar\u00e3o na disputa. O evento tem at\u00e9 o dia 29 para ser encerrado, sempre com a organiza\u00e7\u00e3o escolhendo os melhores dias de ondas.<\/p>\n\n\n\n<p>As baterias ter\u00e3o <strong>transmiss\u00e3o<\/strong> de Sportv, Globoplay e o site da World Surf League.<\/p>\n\n\n\n<p>A \u00faltima etapa do circuito foi disputada em Trestles, na Calif\u00f3rnia, e foi vencida pelo brasileiro Yago Dora, que subiu para a segunda posi\u00e7\u00e3o no ranking. Italo Ferreira, que liderou no in\u00edcio da temporada, \u00e9 agora o quarto na lista.<\/p>\n\n\n\n<p>O evento de Saquarema \u00e9 de amplo dom\u00ednio dos brasileiros, que venceram todos os seis eventos disputados no local. Italo Ferreira \u00e9 o atual vencedor.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Confira as baterias da primeira fase:<\/h3>\n\n\n\n<p><strong>Masculino<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. <strong>Italo Ferreira (BRA)<\/strong> x Connor O&#8217;Leary (JPN) x Seth Moniz (HAV)<\/li>\n\n\n\n<li>2. Kanoa Igarashi (JPN) x Joel Vaughan (AUS) x <strong>Alejo Muniz (BRA)<\/strong><\/li>\n\n\n\n<li><strong>3. Yago Dora (BRA)<\/strong> x Crosby Colapinto (EUA) x <strong>Peterson Crisanto (BRA)<\/strong><\/li>\n\n\n\n<li>4. Jordy Smith (AUS) x Cole Houshmand (EUA) x <strong>Gabriel Klaussner (BRA)<\/strong><\/li>\n\n\n\n<li>5. Barron Mamiya (HAV) x Jake Marshall (EUA) x Alan Cleland (MEX)<\/li>\n\n\n\n<li>6. Ethan Ewing (AUS) x <strong>Miguel Pupo (BRA)<\/strong> x Marco Mignot (FRA)<\/li>\n\n\n\n<li>7. Jack Robinson (AUS) x Leonardo Fioravanti (ITA) x Rio Waida (IND)<\/li>\n\n\n\n<li><strong>8. Filipe Toledo (BRA)<\/strong> x Griffin Colapinto (EUA) x <strong>Jo\u00e3o Chianca (BRA)<\/strong><br><br><strong>Feminino<\/strong><\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>1. Bettylou Sakura Johnson (HAV) x Isabella Nichols (AUS) x Erin Brooks (CAN)<\/li>\n\n\n\n<li>2. Gabriela Bryan (CRC) x Lakey Peterson (EUA) x Arena Rodriguez (PER)<\/li>\n\n\n\n<li>3. Caitlin Simmers (EUA) x Tyler Wright (AUS) x <strong>Tatiana Weston-Webb (BRA)<\/strong><\/li>\n\n\n\n<li>4. Molly Picklum (AUS) x Caroline Marks (EUA) x <strong>Luana Silva (BRA)<\/strong><\/li>\n<\/ul>\n\n\n\n<p>Depois de Saquarema, restar\u00e3o mais duas etapas da temporada regular, que definem os cinco primeiros do ranking. Estes disputar\u00e3o o t\u00edtulo no WSL Finals.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Calend\u00e1rio restante do Circuito Mundial de Surfe<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Etapa 9: Saquarema (BRA), de 21 a 29 de junho<\/li>\n\n\n\n<li>Etapa 10: Jeffreys Bay (AFS), de 11 a 20 de julho<\/li>\n\n\n\n<li>Etapa 11: Teahupoo (TAI), de 7 a 16 de agosto<\/li>\n\n\n\n<li>WSL Finals: Ilhas Fiji, de 27 de agosto a 4 de setembro<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Confira o ranking masculino<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Jordy Smith (AFS) 39.450 pontos<\/li>\n\n\n\n<li><strong>Yago Dora (BRA) 38.885 pontos<\/strong><\/li>\n\n\n\n<li>Kanoa Igarashi (JAP) 36.390 pontos<\/li>\n\n\n\n<li><strong>Italo Ferreira (BRA) 34.610 pontos<\/strong><\/li>\n\n\n\n<li>Barron Mamiya (HAV) 31.470 pontos<\/li>\n<\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Confira o ranking feminino<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Gabriela Bryan (HAV) 45.985 pontos<\/li>\n\n\n\n<li>Caitlin Simmers (EUA) 45.125 pontos<\/li>\n\n\n\n<li>Molly Picklum (AUS) 43.345 pontos<\/li>\n\n\n\n<li>Bettylou Johnson (HAV) 37.320 pontos<\/li>\n\n\n\n<li>Isabella Nichols (AUS) 37.255 pontos<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>A nona etapa do\u00a0Circuito Mundial de Surfe\u00a0come\u00e7a no pr\u00f3ximo s\u00e1bado,\u00a0dia 21, na Praia de Ita\u00fana, em Saquarema. Dez brasileiros estar\u00e3o na disputa. O evento tem at\u00e9 o dia 29 para ser encerrado, sempre com a organiza\u00e7\u00e3o escolhendo os melhores dias de ondas. As baterias ter\u00e3o transmiss\u00e3o de Sportv, Globoplay e o site da World Surf &hellip;<\/p>\n","protected":false},"author":52,"featured_media":217339,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1118,1315],"tags":[1486],"content-tags":[1434],"class_list":["post-217338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outros-esportes","category-surfe","tag-surfe","content-tags-leagues-news","article_type-news","entity_type-competition","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/217338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=217338"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/217338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/217339"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=217338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=217338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=217338"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=217338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}