{"id":214473,"date":"2025-05-15T17:41:22","date_gmt":"2025-05-15T20:41:22","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=214473"},"modified":"2025-05-16T08:54:47","modified_gmt":"2025-05-16T11:54:47","slug":"vila-nova-x-athletico-horario-escalacoes-e-onde-assistir","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/vila-nova-x-athletico-horario-escalacoes-e-onde-assistir\/","title":{"rendered":"Vila Nova x Athletico: hor\u00e1rio, escala\u00e7\u00f5es e onde assistir"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao---serie-b-superbet-116\/athletico-paranaense-vila-nova-1210-1782-116#id=4384412\" target=\"_blank\" rel=\"noreferrer noopener\">Vila Nova x Athletico<\/a>\u00a0se enfrentam neste s\u00e1bado (17), \u00e0s 18h30 (de Bras\u00edlia), pela oitava rodada da <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/brasileirao---serie-b-superbet-116\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e9rie B do Campeonato Brasileiro.<\/a> A partida ser\u00e1 realizada no Est\u00e1dio On\u00e9sio Brasileiro Alvarenga, em Goi\u00e2nia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Vila Nova<\/h2>\n\n\n\n<p>Terceiro colocado da S\u00e9rie B com 13 pontos, o Vila Nova perdeu apenas dois jogos nas primeiras sete rodadas, mas a \u00faltima foi justamente no meio da semana. Os goianos perderam por 2 a 0 para o Remo, fora de casa. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Athletico<\/h2>\n\n\n\n<p>Enquanto isso, o Furac\u00e3o, que j\u00e1 trocou de comando na competi\u00e7\u00e3o, est\u00e1 apenas na nona posi\u00e7\u00e3o, com 10 pontos. Entretanto, o rubro-negro vem de tr\u00eas jogos sem vit\u00f3ria e empatou com a Chapecoense em 1 a 1 no \u00faltimo fim de semana. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escala\u00e7\u00f5es de Vila Nova x Athletico<\/h2>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Vila Nova<\/strong>: Halls; Elias, Tiago Pagnussat, Bernardo Schappo e Willian Formiga; Jo\u00e3o Vieira, Igor Henrique (Arilson) e Diego Torres; Vin\u00edcius Paiva, Gabriel Poveda e Gabriel Silva.&nbsp;<strong>T\u00e9cnico<\/strong>: Rafael Lacerda <\/p>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Athletico<\/strong>: Mycael; Belezi (Palacios ou Dudu), Habra\u00e3o, L\u00e9o e Esquivel; Felipinho, Patrick e Zapelli; Isaac (Tevis), Luiz Fernando e Renan Peixoto.&nbsp;<strong>T\u00e9cnico<\/strong>: Jo\u00e3o Correia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir a Vila Nova x Athletico<\/h2>\n\n\n\n<p>A partida entre&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao---serie-b-superbet-116\/athletico-paranaense-vila-nova-1210-1782-116#id=4384412\" target=\"_blank\" rel=\"noreferrer noopener\">Vila Nova x Athletico&nbsp;<\/a>ter\u00e1 transmiss\u00e3o da Paramount+. O&nbsp;<strong>365Scores<\/strong>&nbsp;tamb\u00e9m far\u00e1 a cobertura em tempo real,&nbsp;al\u00e9m de disponibilizar onde assistir aos&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\">jogos de hoje na TV.<\/a><\/p>\n\n\n\n<div data-widget-type=\"game\" data-widget-id=\"0.nfbeka3t3c\" data-lang=\"pt-PT\" data-entity-id=\"1210-1782-116\" data-user-country-id=\"21\" data-publisher-id=\"2\" data-hide-powered-by=\"true\"><\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\"><\/script>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha t\u00e9cnica \u2013 Vila Nova x Athletico<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data<\/strong>: 15\/05\/2025<\/li>\n\n\n\n<li><strong>Hor\u00e1rio<\/strong>: 21h30 (de Bras\u00edlia)<\/li>\n\n\n\n<li><strong>Local<\/strong>: On\u00e9sio Brasileiro Alvarenga &#8211; Goiania &#8211; GO<\/li>\n\n\n\n<li><strong>\u00c1rbitro:<\/strong> Lucas Canetto Bellote<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Vila Nova<\/strong>: Halls; Elias, Tiago Pagnussat, Bernardo Schappo e Willian Formiga; Jo\u00e3o Vieira, Igor Henrique (Arilson) e Diego Torres; Vin\u00edcius Paiva, Gabriel Poveda e Gabriel Silva<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Vila Nova<\/strong>: Rafael Lacerda <\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Athletico<\/strong>: Mycael; Belezi (Palacios ou Dudu), Habra\u00e3o, L\u00e9o e Esquivel; Felipinho, Patrick e Zapelli; Isaac (Tevis), Luiz Fernando e Renan Peixoto<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Athletico<\/strong>: Jo\u00e3o Correia<\/li>\n\n\n\n<li><strong>Onde assistir<\/strong>: ESPN, Disney+ e 365Scores<\/li>\n<\/ul>\n\n\n\n<p><em><strong>N\u00e3o quer perder nenhum&nbsp;<\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>placar de futebol<\/em><\/strong><\/a><em><strong>&nbsp;ou os&nbsp;<\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de hoje na tv<\/em><\/strong><\/a><em><strong>? Fique por dentro acessando o site do 365Scores: resultado ao vivo,&nbsp;<\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos em andamento<\/em><\/strong><\/a><em><strong>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vila Nova x Athletico\u00a0se enfrentam neste s\u00e1bado (17), \u00e0s 18h30 (de Bras\u00edlia), pela oitava rodada da S\u00e9rie B do Campeonato Brasileiro. A partida ser\u00e1 realizada no Est\u00e1dio On\u00e9sio Brasileiro Alvarenga, em Goi\u00e2nia. Como chega o Vila Nova Terceiro colocado da S\u00e9rie B com 13 pontos, o Vila Nova perdeu apenas dois jogos nas primeiras sete &hellip;<\/p>\n","protected":false},"author":27,"featured_media":214385,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1126,7],"tags":[1390,166],"content-tags":[1352],"class_list":["post-214473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasileiro-serie-b","category-futebol","tag-athletico","tag-futebol-brasileiro","content-tags-game-preview","article_type-news","entity_type-match","inspiration-365s-articles"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/214473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=214473"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/214473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/214385"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=214473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=214473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=214473"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=214473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}