{"id":206150,"date":"2025-01-28T14:35:52","date_gmt":"2025-01-28T17:35:52","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=206150"},"modified":"2025-01-28T15:36:12","modified_gmt":"2025-01-28T18:36:12","slug":"tottenham-x-elfsborg-horario-escalacoes-onde-assistir-ao-jogo-da-liga-europa","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/tottenham-x-elfsborg-horario-escalacoes-onde-assistir-ao-jogo-da-liga-europa\/","title":{"rendered":"Tottenham x Elfsborg: hor\u00e1rio, escala\u00e7\u00f5es, onde assistir ao jogo da Liga Europa"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/uefa-europa-league-573\/if-elfsborg-tottenham-114-1889-573#id=4216920\" target=\"_blank\" rel=\"noreferrer noopener\">Tottenham x Elfsborg<\/a>&nbsp;se enfrentam nesta quinta-feira (30), \u00e0s 17h00 (de Bras\u00edlia), pela 8\u00aa rodada da fase de liga da&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/uefa-europa-league-573\" target=\"_blank\" rel=\"noreferrer noopener\">Uefa Europa League<\/a>. A partida ser\u00e1 realizada no Tottenham Hotspur Stadium, em Londres.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Tottenham<\/h2>\n\n\n\n<p>Sexto colocado da Liga Europa, o Tottenham quer se garantir de forma direta nas oitavas de final da competi\u00e7\u00e3o. Ao in\u00edcio da rodada, os Spurs somam 14 pontos e precisam de apenas uma vit\u00f3ria para terminar no G8. Em caso de empate ou derrota, depender\u00e1 de outros resultados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Elfsborg<\/h2>\n\n\n\n<p>20\u00ba colocado, o Elfsborg \u00e9 outro que ainda briga por vaga na pr\u00f3xima fase da Liga Europa. A equipe sueca soma 10 pontos, dois a mais que o Porto, primeiro time fora da zona de classifica\u00e7\u00e3o para a repescagem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escala\u00e7\u00f5es: Tottenham x Elfsborg<\/h2>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Tottenham:<\/strong>&nbsp;Kinsky, Gray, Davies, Dragusin e Pedro Porro; Bergvall, Bentancur e Sarr; Son, Kulusevski e Richarlison.&nbsp;<strong>T\u00e9cnico<\/strong>: Ange Postecoglou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"572\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101208.png\" alt=\"\" class=\"wp-image-206151\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101208.png 714w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101208-300x240.png 300w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Elfsborg:<\/strong>&nbsp;Petterson, Yegbe, Holmen e Henriksson; Hult, Qasem, Zeneli e Hedlund; Rapp, Abdullai e Zeneli.&nbsp;<strong>T\u00e9cnico<\/strong>: Oscar Hiljemark.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"572\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101216.png\" alt=\"\" class=\"wp-image-206152\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101216.png 721w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2025\/01\/Captura-de-tela-2025-01-28-101216-300x238.png 300w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir Tottenham x Elfsborg<\/h2>\n\n\n\n<p>A partida entre Tottenham x Elfsborg ter\u00e1 transmiss\u00e3o da Caz\u00e9TV (YouTube) e cobertura em tempo real do 365Scores, al\u00e9m de disponibilizar&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/where-to-watch\" target=\"_blank\" rel=\"noreferrer noopener\">onde assistir aos jogos na TV<\/a>.<\/p>\n\n\n\n<div data-widget-type=\"game\" data-widget-id=\"0.u1zs3mjjod\" data-lang=\"pt-BR\" data-entity-id=\"114-1889-573\" data-user-country-id=\"21\" data-publisher-id=\"2\" data-hide-powered-by=\"true\"><\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\"><\/script>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha t\u00e9cnica \u2013 Tottenham x Elfsborg<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data<\/strong>: 30\/01\/2025<\/li>\n\n\n\n<li><strong>Hor\u00e1rio<\/strong>: 17h00 (de Bras\u00edlia)<\/li>\n\n\n\n<li><strong>Local<\/strong>: Tottenham Hotspur Stadium, Londres<\/li>\n\n\n\n<li><strong>Rodada<\/strong>: 8\u00aa rodada<\/li>\n\n\n\n<li><strong>\u00c1rbitro<\/strong>:&nbsp;Sebastian Gishamer&nbsp;(\u00c1ustria)<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Tottenham:<\/strong>&nbsp;Kinsky, Gray, Davies, Dragusin e Pedro Porro; Bergvall, Bentancur e Sarr; Son, Kulusevski e Richarlison<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Tottenham<\/strong>: Ange Postecoglou<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Elfsborg:<\/strong>&nbsp;Petterson, Yegbe, Holmen e Henriksson; Hult, Qasem, Zeneli e Hedlund; Rapp, Abdullai e Zeneli<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Elfsborg<\/strong>: Oscar Hiljemark<\/li>\n\n\n\n<li><strong>Onde assistir<\/strong>: Caz\u00e9TV e 365Scores<\/li>\n<\/ul>\n\n\n\n<p><strong><em>N\u00e3o quer perder nenhum&nbsp;placar de futebol&nbsp;ou os&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/tomorrows-matches\" target=\"_blank\" rel=\"noreferrer noopener\">jogos de amanh\u00e3<\/a>? Fique por dentro acessando o site do 365scores: resultado ao vivo,&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\">jogos em andamento<\/a>&nbsp;e muito mais!<\/em><\/strong><\/p>\n\n\n\n<div\n    data-scores-container-id=\"widgets-samples\"\n    data-widget-type=\"predictions\"\n    data-entity-type=\"team\"\n    data-show-powered-by=\"true\"\n    data-publisher-id=\"2\"\n    data-user-country-id=\"21\"\n    data-entity-id=\"114\"\n    data-show-odds=\"true\"\n    data-show-sponsorship=\"true\"\n    data-enable-impression-count=\"true\"\n    data-allow-insight=\"true\"\n    data-lang=\"pt-BR\">\n<\/div>\n<script\n    src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Tottenham x Elfsborg&nbsp;se enfrentam nesta quinta-feira (30), \u00e0s 17h00 (de Bras\u00edlia), pela 8\u00aa rodada da fase de liga da&nbsp;Uefa Europa League. A partida ser\u00e1 realizada no Tottenham Hotspur Stadium, em Londres. Como chega o Tottenham Sexto colocado da Liga Europa, o Tottenham quer se garantir de forma direta nas oitavas de final da competi\u00e7\u00e3o. Ao &hellip;<\/p>\n","protected":false},"author":25,"featured_media":206154,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1114,1134],"tags":[],"content-tags":[1354],"class_list":["post-206150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol-internacional","category-liga-europa","content-tags-where-to-watch"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/206150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=206150"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/206150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/206154"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=206150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=206150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=206150"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=206150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}