{"id":200987,"date":"2024-11-05T15:11:33","date_gmt":"2024-11-05T18:11:33","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=200987"},"modified":"2024-11-05T15:12:07","modified_gmt":"2024-11-05T18:12:07","slug":"benzema-destaca-dificuldade-de-mbappe-no-real-madrid-nao-e-um-9","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/benzema-destaca-dificuldade-de-mbappe-no-real-madrid-nao-e-um-9\/","title":{"rendered":"Benzema destaca dificuldade de Mbapp\u00e9 no Real Madrid: &#8220;N\u00e3o \u00e9 um 9&#8221;"},"content":{"rendered":"\n<p>Ex-jogador do <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/real-madrid-131\" target=\"_blank\" rel=\"noreferrer noopener\">Real Madrid<\/a>, <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/karim-benzema-543\" target=\"_blank\" rel=\"noreferrer noopener\">Karim Benzema<\/a> parece saber das dificuldades que <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/kylian-mbappe-39820\" target=\"_blank\" rel=\"noreferrer noopener\">Kylian Mbapp\u00e9<\/a> enfrenta no come\u00e7o de sua passagem pelo clube merengue. Em entrevista ao &#8220;El Chiringuito&#8221;, <strong>o jogador do Al Ittihad afirmou que o camisa 9 precisa aceitar que ele \u00e9 um centroavante e lidar com a press\u00e3o dos torcedores<\/strong>.<\/p>\n\n\n\n<p>&#8220;Para mim, Mbapp\u00e9 n\u00e3o \u00e9 um centroavante. Quando joga como atacante pela sele\u00e7\u00e3o, ele n\u00e3o tem um bom desempenho. Essa n\u00e3o \u00e9 a sua posi\u00e7\u00e3o. Mas pelo lado esquerdo, Vinicius est\u00e1 no mesmo n\u00edvel que ele. Voc\u00ea n\u00e3o pode mover Vinicius para jogar como atacante ou pelo lado direito porque ele faz a diferen\u00e7a em cada partida pela esquerda. \u00c9 um problema&#8221;, disse Benzema.<\/p>\n\n\n\n<p>&#8220;Ancelotti sabe muito e encontrar\u00e1 uma maneira de solucionar isso. Mbapp\u00e9 n\u00e3o \u00e9 um n\u00famero 9. As pessoas exigem muito dele, colocando-o sob press\u00e3o. Isso n\u00e3o \u00e9 o PSG. Cheguei com 21 anos, Kylian com 25. N\u00e3o \u00e9 a mesma coisa. H\u00e1 muita press\u00e3o em Madrid. Ele precisa aprender a conviver com isso. Ele precisa fazer gols. Trouxeram ele para fazer gols. Ele tem habilidade para fazer isso&#8221;, continuou.<\/p>\n\n\n\n<p>Al\u00e9m disso, Benzema destacou Vini Jr. como o melhor jogador do mundo. Para ele, o camisa 7 do Real Madrid n\u00e3o deveria mudar de posi\u00e7\u00e3o.<\/p>\n\n\n\n<p>&#8220;Ele n\u00e3o deve jogar a toalha. N\u00e3o acho que Vinicius mudar\u00e1 de posi\u00e7\u00e3o porque ele \u00e9 o melhor do mundo no momento. Kylian precisa aceitar que ele \u00e9 um nove agora e esquecer de jogar pelo lado esquerdo&#8221;, concluiu Benzema.<\/p>\n\n\n\n<p>Na temporada, Mbapp\u00e9 possui 14 jogos pelo Real Madrid, oito gols marcados e duas assist\u00eancias dadas. Os n\u00fameros s\u00e3o bons, mas o desempenho recente do clube n\u00e3o impressiona. A equipe est\u00e1 na 12\u00aa coloca\u00e7\u00e3o na Fase de Liga da Champions League e \u00e9 vice-l\u00edder do Campeonato Espanhol com nove pontos.<\/p>\n\n\n\n<p><em><strong>Para saber tudo sobre os <\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\"><strong><em>jogos ao vivo <\/em><\/strong><\/a><em><strong>do futebol brasileiro e do mundo de hoje, acesse o 365Scores. Acompanhe as classifica\u00e7\u00f5es, transfer\u00eancias, rumores, not\u00edcias, estat\u00edsticas e muito mais!<\/strong><\/em><\/p>\n\n\n\n<div\n    data-scores-container-id=\"widgets-samples\"\n    data-widget-type=\"predictions\"\n    data-entity-type=\"team\"\n    data-show-powered-by=\"true\"\n    data-publisher-id=\"2\"\n    data-user-country-id=\"21\"\n    data-entity-id=\"131\"\n    data-show-odds=\"true\"\n    data-show-sponsorship=\"true\"\n    data-enable-impression-count=\"true\"\n    data-allow-insight=\"true\"\n    data-lang=\"pt-BR\">\n<\/div>\n<script\n    src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Ex-jogador do Real Madrid, Karim Benzema parece saber das dificuldades que Kylian Mbapp\u00e9 enfrenta no come\u00e7o de sua passagem pelo clube merengue. Em entrevista ao &#8220;El Chiringuito&#8221;, o jogador do Al Ittihad afirmou que o camisa 9 precisa aceitar que ele \u00e9 um centroavante e lidar com a press\u00e3o dos torcedores. &#8220;Para mim, Mbapp\u00e9 n\u00e3o &hellip;<\/p>\n","protected":false},"author":28,"featured_media":200990,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1114,1133],"tags":[],"content-tags":[1346],"class_list":["post-200987","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol-internacional","category-liga-dos-campeoes","content-tags-general-news"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/200987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=200987"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/200987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/200990"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=200987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=200987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=200987"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=200987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}