{"id":197354,"date":"2024-09-20T12:32:21","date_gmt":"2024-09-20T15:32:21","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=197354"},"modified":"2024-09-20T13:26:35","modified_gmt":"2024-09-20T16:26:35","slug":"vasco-palmeiras-onde-assistir-escalacoes","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/vasco-palmeiras-onde-assistir-escalacoes\/","title":{"rendered":"Vasco x Palmeiras: hor\u00e1rio, prov\u00e1veis escala\u00e7\u00f5es e onde assistir ao duelo do Brasileir\u00e3o"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/palmeiras-vasco-da-gama-1222-1227-113#id=4057901\" target=\"_blank\" rel=\"noreferrer noopener\">Vasco e Palmeiras<\/a> se enfrentam neste domingo, \u00e0s 16h (de Bras\u00edlia), pela 27\u00aa rodada do Brasileir\u00e3o. A partida ser\u00e1 realizada no est\u00e1dio Man\u00e9 Garrincha, em Bras\u00edlia. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Por que Vasco x Palmeiras ser\u00e1 em Bras\u00edlia?<\/h2>\n\n\n\n<p>Alguns torcedores foram pegos de surpresa quando a CBF confirmou a disputa entre <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/palmeiras-vasco-da-gama-1222-1227-113#id=4057901\" target=\"_blank\" rel=\"noreferrer noopener\">Vasco e Palmeiras<\/a> no Man\u00e9 Garrincha, em Bras\u00edlia. A venda do jogo foi feita na gest\u00e3o de L\u00facio Barbosa, no per\u00edodo sob o comando da 777 Partners, no in\u00edcio do ano. Inclusive, o dinheiro foi antecipado pela antiga dire\u00e7\u00e3o do Vasco para que o jogo fosse realizado em Bras\u00edlia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Vasco<\/h2>\n\n\n\n<p>Embalado por um empate com o Flamengo, no Maracan\u00e3, na \u00faltima rodada do Brasileir\u00e3o e uma classifica\u00e7\u00e3o importante \u00e0s semifinais da Copa do Brasil, o <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/vasco-da-gama-1227\" target=\"_blank\" rel=\"noreferrer noopener\">Vasco<\/a> chega para o duelo na busca pelos tr\u00eas pontos para se manter no topo da tabela. Philippe Coutinho \u00e9 uma das surpresas do Vasco.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como chega o Palmeiras<\/h2>\n\n\n\n<p>Vice-l\u00edder do Brasileir\u00e3o e focado apenas na competi\u00e7\u00e3o nacional, o <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/palmeiras-1222\" target=\"_blank\" rel=\"noreferrer noopener\">Palmeiras<\/a> chega para o duelo ap\u00f3s golear o Crici\u00fama por 5 a 0. No entanto, Est\u00eav\u00e3o, um dos principais nomes do time, foi diagnosticado com grave les\u00e3o e vai ser baixa no duelo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Escala\u00e7\u00f5es &#8211; Vasco x Palmeiras<\/h2>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Vasco:<\/strong> L\u00e9o Jardim; Paulo Henrique, Maicon, L\u00e9o e Lucas Piton; Hugo Moura, Sforza, Jean, David e Payet; Vegetti.&nbsp;<strong>T\u00e9cnico<\/strong>: Rafael Paiva.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"684\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-250.png\" alt=\"\" class=\"wp-image-197358\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-250.png 920w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-250-300x223.png 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-250-768x571.png 768w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/figure>\n\n\n\n<p><strong>Prov\u00e1vel escala\u00e7\u00e3o do Palmeiras<\/strong>: Weverton; Marcos Rocha, G\u00f3mez, Murilo e Vanderlan; An\u00edbal Moreno, Richard R\u00edos, Dudu, Maur\u00edcio, Felipe Anderson; L\u00f3pez.&nbsp;<strong>T\u00e9cnico<\/strong>: Abel Ferreira.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"927\" height=\"682\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-251.png\" alt=\"\" class=\"wp-image-197359\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-251.png 927w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-251-300x221.png 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/09\/image-251-768x565.png 768w\" sizes=\"auto, (max-width: 927px) 100vw, 927px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir Vasco x Palmeiras<\/h2>\n\n\n\n<p>A partida entre Vasco e Palmeiras ser\u00e1 transmitida pelos canais fechados Premiere e Sportv e pelo streaming Amazon Prime. O <strong>365Scores <\/strong>tamb\u00e9m far\u00e1 a cobertura em tempo real.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ficha t\u00e9cnica &#8211; Vasco x Palmeiras<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Data<\/strong>: 22\/09\/2024<\/li>\n\n\n\n<li><strong>Hor\u00e1rio<\/strong>: 16h (de Bras\u00edlia)<\/li>\n\n\n\n<li><strong>Local<\/strong>: Man\u00e9 Garrincha, Bras\u00edlia<\/li>\n\n\n\n<li><strong>\u00c1rbitro<\/strong>: Rafael Rodrigo Klein<\/li>\n\n\n\n<li><strong>Assistentes<\/strong>: Rafael da Silva Alves e Michael Stanislau; Marcello Ruda Neves Ramos da Costa (quarto \u00e1rbitro)<\/li>\n\n\n\n<li><strong>VAR<\/strong>: Gilberto Rodrigues Castro Junior;<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Vasco:<\/strong> L\u00e9o Jardim; Paulo Henrique, Maicon, L\u00e9o e Lucas Piton; Hugo Moura, Sforza, Jean, David e Payet; Vegetti<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Vasco:<\/strong> Rafael Paiva<\/li>\n\n\n\n<li><strong>Prov\u00e1vel escala\u00e7\u00e3o do Palmeiras:<\/strong> Weverton; Marcos Rocha, G\u00f3mez, Murilo e Vanderlan; An\u00edbal Moreno, Richard R\u00edos e Maur\u00edcio; Felipe Anderson, Rony (L\u00e1zaro) e L\u00f3pez<\/li>\n\n\n\n<li><strong>T\u00e9cnico do Palmeiras:<\/strong> Abel Ferreira<\/li>\n\n\n\n<li><strong>Onde assistir:<\/strong> Premiere, Sportv, Amazon Prime e 365Scores.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Tabela de Classifica\u00e7\u00e3o do Campeonato Brasileiro<\/h2>\n\n\n\n<div data-widget-type=\"entityStandings\" data-entity-type=\"league\" data-widget-id=\"0.0dn5amd1ryk\" data-lang=\"pt-PT\" data-entity-id=\"113\"><\/div>\ntarget=&#8221;_blank&#8221;>365Scores.com<\/a><\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\"><\/script>\n","protected":false},"excerpt":{"rendered":"<p>Vasco e Palmeiras se enfrentam neste domingo, \u00e0s 16h (de Bras\u00edlia), pela 27\u00aa rodada do Brasileir\u00e3o. A partida ser\u00e1 realizada no est\u00e1dio Man\u00e9 Garrincha, em Bras\u00edlia. Por que Vasco x Palmeiras ser\u00e1 em Bras\u00edlia? Alguns torcedores foram pegos de surpresa quando a CBF confirmou a disputa entre Vasco e Palmeiras no Man\u00e9 Garrincha, em Bras\u00edlia. &hellip;<\/p>\n","protected":false},"author":41,"featured_media":197356,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1125,7],"tags":[172,73],"content-tags":[1352],"class_list":["post-197354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasileiro-serie-a","category-futebol","tag-palmeiras","tag-vasco","content-tags-game-preview"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/197354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=197354"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/197354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/197356"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=197354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=197354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=197354"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=197354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}