{"id":192150,"date":"2024-07-21T09:32:45","date_gmt":"2024-07-21T12:32:45","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=192150"},"modified":"2024-07-21T09:32:49","modified_gmt":"2024-07-21T12:32:49","slug":"jogador-do-criciuma-explica-penalti-polemico-para-o-flamengo-e-admite-que-nao-conhecia-a-regra","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/jogador-do-criciuma-explica-penalti-polemico-para-o-flamengo-e-admite-que-nao-conhecia-a-regra\/","title":{"rendered":"Jogador do Crici\u00fama explica p\u00eanalti pol\u00eamico para o Flamengo e admite que n\u00e3o conhecia a regra"},"content":{"rendered":"\n<p>A partida entre Flamengo e Crici\u00fama, pela 18\u00aa rodada do Brasileir\u00e3o, chamou a aten\u00e7\u00e3o por uma marca\u00e7\u00e3o incomum de p\u00eanalti. O volante Barreto, do time catarinense, admitiu que chutou a segunda bola de prop\u00f3sito, mas que n\u00e3o conhecia a regra da penalidade.<\/p>\n\n\n\n<p>O jogador do Crici\u00fama disse que chutou a bola em cima da outra, que estava com Everton Cebolinha, justamente para alertar a arbitragem que haviam duas bolas em campo. No entanto, ele impediu o ataque rubro-negro e foi marcada o segundo p\u00eanalti do jogo.<\/p>\n\n\n\n<p>&#8220;Foi um lance bizarro. Na minha cabe\u00e7a, no momento, foi instinto. Quando eu vi a segunda bola em campo, eu tinha na cabe\u00e7a que duas bolas envolvendo o lance n\u00e3o podia. Eu chutei contra o advers\u00e1rio realmente para o juiz notar que tinha duas bolas, ent\u00e3o claro n\u00e3o sabia que iria ser p\u00eanalti, se n\u00e3o eu n\u00e3o faria. A minha inten\u00e7\u00e3o na hora realmente foi bem instintiva. Jamais prejudicaria meus companheiros, a gente sabia da dificuldade&#8221;.<\/p>\n\n\n\n<p>O duelo estava em 1 a 1, quando o volante carvoeiro fez o lance e o \u00e1rbitro Maguielson Lima Barbosa marcou p\u00eanalti. O Flamengo converteu, chegou ao segundo gol e de virada conquistou os tr\u00eas pontos em Bras\u00edlia. Pedro, inclusive, j\u00e1 havia desperdi\u00e7ado um p\u00eanalti antes do lance. <\/p>\n\n\n\n<p>Ap\u00f3s o apito final, o goleiro do Crici\u00fama afirmou que o sentimento \u00e9 de \u201cindigna\u00e7\u00e3o e frustra\u00e7\u00e3o\u201d. <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/penalti-marcado-para-o-flamengo-repercute-nas-redes-sociais\/\" target=\"_blank\" rel=\"noreferrer noopener\">O lance repercutiu nas redes sociais.<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Regras para tiro livre direto<\/h2>\n\n\n\n<p>Um tiro livre direto ser\u00e1 concedido se um jogador cometer uma das seguintes infra\u00e7\u00f5es<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Uma infra\u00e7\u00e3o por toque de m\u00e3o na bola (com exce\u00e7\u00e3o do goleiro no interior da pr\u00f3pria \u00e1rea penal);<\/li>\n\n\n\n<li>Segurar um advers\u00e1rio;<\/li>\n\n\n\n<li>Impedir o movimento de um advers\u00e1rio com contato f\u00edsico;<\/li>\n\n\n\n<li>Morder ou cuspir em algu\u00e9m inscrito na rela\u00e7\u00e3o de ambas as equipes ou em um membro da equipe de arbitragem;<\/li>\n\n\n\n<li>Arremessar um objeto na dire\u00e7\u00e3o da bola, de um advers\u00e1rio ou de um membro da equipe de arbitragem ou tocar na bola com um objeto. <\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Veja o lance:<\/h2>\n\n\n\n<p>A CBF divulgou a comunica\u00e7\u00e3o do VAR no lance do p\u00eanalti para o Flamengo.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">A CBF divulgou a comunica\u00e7\u00e3o do VAR no lance do p\u00eanalti para o Flamengo.<br><br>O que acharam? <a href=\"https:\/\/t.co\/FgfvljiIeE\">pic.twitter.com\/FgfvljiIeE<\/a><\/p>&mdash; Yara Fantoni (@yarafantoni) <a href=\"https:\/\/twitter.com\/yarafantoni\/status\/1814815510371913848?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 21, 2024<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p><strong><em>A<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/temporada-flamengo\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;temporada do Flameng<\/a>o j\u00e1 come\u00e7ou! Entre no site do 365Scores e fique por dentro de todas as novidades atualizadas: tabela de classifica\u00e7\u00e3o, estat\u00edsticas, elenco, transfer\u00eancias, jogos de hoje e mais!<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partida entre Flamengo e Crici\u00fama, pela 18\u00aa rodada do Brasileir\u00e3o, chamou a aten\u00e7\u00e3o por uma marca\u00e7\u00e3o incomum de p\u00eanalti. O volante Barreto, do time catarinense, admitiu que chutou a segunda bola de prop\u00f3sito, mas que n\u00e3o conhecia a regra da penalidade. O jogador do Crici\u00fama disse que chutou a bola em cima da outra, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":192151,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1125],"tags":[],"content-tags":[],"class_list":["post-192150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-a"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/192150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=192150"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/192150\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/192151"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=192150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=192150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=192150"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=192150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}