{"id":191901,"date":"2024-07-17T14:43:30","date_gmt":"2024-07-17T17:43:30","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=191901"},"modified":"2024-07-17T15:46:20","modified_gmt":"2024-07-17T18:46:20","slug":"textor-do-botafogo-faz-revelacao-sobre-abel-ferreira-tentei-contrata-lo","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/textor-do-botafogo-faz-revelacao-sobre-abel-ferreira-tentei-contrata-lo\/","title":{"rendered":"Textor, do Botafogo, faz revela\u00e7\u00e3o sobre Abel Ferreira: &#8220;Tentei contrat\u00e1-lo&#8221;"},"content":{"rendered":"\n<p>Em v\u00e9spera de <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/botafogo-palmeiras-1211-1222-113#id=4057830\" target=\"_blank\" rel=\"noreferrer noopener\">Botafogo e Palmeiras<\/a> pelo <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/league\/brasileirao-serie-a-113\" target=\"_blank\" rel=\"noreferrer noopener\">Campeonato Brasileiro <\/a>de 2024, John Textor fez uma revela\u00e7\u00e3o sobre <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/abel-ferreira-48619\" target=\"_blank\" rel=\"noreferrer noopener\">Abel Ferreira<\/a>. Segundo o empres\u00e1rio americano, uma tentativa pela contrata\u00e7\u00e3o do treinador alviverde ocorreu, mas o portugu\u00eas n\u00e3o aceitou. <\/p>\n\n\n\n<p>&#8220;Intensa ambi\u00e7\u00e3o, n\u00e3o vingan\u00e7a. Todos os fatores fora de campo que podem trazer esse sentimento de vingan\u00e7a n\u00e3o t\u00eam nada a ver com os jogadores. Eu admiro o Abel. Tentei contrat\u00e1-lo, ele disse n\u00e3o repetidamente&#8221;, afirmou Textor. <\/p>\n\n\n\n<p>Al\u00e9m disso, o dono da SAF do Botafogo aproveitou para enaltecer o elenco e a base do Palmeiras, que est\u00e3o brigando por t\u00edtulos e formam um dos principais elencos do futebol brasileiro h\u00e1 algumas temporadas. <\/p>\n\n\n\n<p>&#8220;Os jogadores e a base do Palmeiras s\u00e3o fant\u00e1sticos. Eu compro jogadores de 20 milh\u00f5es (de euros) para competir com algu\u00e9m que eles formam na pr\u00f3pria casa, porque n\u00f3s somos novos nisso. Eles s\u00e3o favoritos todos os anos, ent\u00e3o voc\u00ea quer vencer o melhor time&#8221;, concluiu. <\/p>\n\n\n\n<p>Vale lembrar que o confronto entre as equipes vale a lideran\u00e7a do Campeonato Brasileiro. Ambos est\u00e3o com 33 pontos, mas o Botafogo leva vantagem em crit\u00e9rios de desempate. O duelo est\u00e1 marcado para quarta-feira (17), \u00e0s 21h30 (de Bras\u00edlia), no Est\u00e1dio Nilton Santos. <\/p>\n\n\n\n<p><strong><em>A <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/temporada-botafogo\/\" target=\"_blank\" rel=\"noreferrer noopener\">temporada do Botafogo<\/a> j\u00e1 come\u00e7ou! Entre no site do 365Scores e fique por dentro de todas as novidades atualizadas: tabela de classifica\u00e7\u00e3o, estat\u00edsticas, elenco, transfer\u00eancias, jogos de hoje e mais!<\/em><\/strong><\/p>\n\n\n\n<div\n    data-scores-container-id=\"widgets-samples\"\n    data-widget-type=\"predictions\"\n    data-entity-type=\"team\"\n    data-show-powered-by=\"true\"\n    data-publisher-id=\"2\"\n    data-user-country-id=\"21\"\n    data-entity-id=\"1211\"\n    data-show-odds=\"true\"\n    data-show-sponsorship=\"true\"\n    data-enable-impression-count=\"true\"\n    data-allow-insight=\"true\"\n    data-lang=\"pt-BR\">\n<\/div>\n<script\n    src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n\n","protected":false},"excerpt":{"rendered":"<p>Em v\u00e9spera de Botafogo e Palmeiras pelo Campeonato Brasileiro de 2024, John Textor fez uma revela\u00e7\u00e3o sobre Abel Ferreira. Segundo o empres\u00e1rio americano, uma tentativa pela contrata\u00e7\u00e3o do treinador alviverde ocorreu, mas o portugu\u00eas n\u00e3o aceitou. &#8220;Intensa ambi\u00e7\u00e3o, n\u00e3o vingan\u00e7a. Todos os fatores fora de campo que podem trazer esse sentimento de vingan\u00e7a n\u00e3o t\u00eam &hellip;<\/p>\n","protected":false},"author":2,"featured_media":183363,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1125],"tags":[],"content-tags":[],"class_list":["post-191901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-a"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/191901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=191901"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/191901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/183363"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=191901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=191901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=191901"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=191901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}