{"id":183860,"date":"2024-04-15T08:25:38","date_gmt":"2024-04-15T11:25:38","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=183860"},"modified":"2024-04-15T16:28:03","modified_gmt":"2024-04-15T19:28:03","slug":"selecao-365-scores-1-rodada-brasileirao","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/selecao-365-scores-1-rodada-brasileirao\/","title":{"rendered":"Brasileir\u00e3o 2024: confira a Time da Rodada 365Scores"},"content":{"rendered":"\n<p>O <a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/brasileirao-onde-assistir-jogos-datas\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brasileir\u00e3o 2024<\/a> oficialmente come\u00e7ou. Com dez partidas e 28 gols marcados, os 20 principais times do pa\u00eds voltaram \u00e0 a\u00e7\u00e3o em busca do trof\u00e9u mais cobi\u00e7ado do ano. Apesar dos resultados nem t\u00e3o positivos, os cariocas foram os destaques da <strong>Time da Rodada 365Scores<\/strong>.<\/p>\n\n\n\n<p>Protagonista do <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/fluminense-rb-bragantino-1216-1273-113#id=4057578\" target=\"_blank\" rel=\"noreferrer noopener\">primeiro grande jogo no s\u00e1bado<\/a> (13), o Fluminense contou com dois jogadores na sele\u00e7\u00e3o: <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/ganso-3106\" target=\"_blank\" rel=\"noreferrer noopener\">Ganso<\/a> e <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/lima-50002\" target=\"_blank\" rel=\"noreferrer noopener\">Lima<\/a>, que foi o jogador com maior nota entre todos (9.2). <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/botafogo-cruzeiro-1211-1213-113#id=4057576\" target=\"_blank\" rel=\"noreferrer noopener\">O Botafogo, derrotado por 3 a 2 pelo Cruzeiro<\/a>, teve dois jogadores (Danilo Barbosa e Hugo) e o t\u00e9cnico da equipe ideal (Artur Jorge).<\/p>\n\n\n\n<p>Ainda no empate entre Fluminense e RB Bragantino, dois jogadores representaram o Massa Bruta: Vitinho e Thiago Borbas. <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/brasileirao-serie-a-113\/athletico-paranaense-cuiaba-1210-9188-113#id=4057590\" target=\"_blank\" rel=\"noreferrer noopener\">O Athletico-PR, que goleou o Cuiab\u00e1 por 4 a 0,<\/a> tamb\u00e9m teve dois: Canobbio e Fernandinho. William (Cruzeiro), Gustavo Martins (Gr\u00eamio) e Weverton (Palmeiras) completam o time.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Confira a Time da Rodada 365Scores do Brasileir\u00e3o:<\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"1024\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/04\/photo_2024-04-15_08-14-29-784x1024.jpg\" alt=\"\" class=\"wp-image-183861\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/04\/photo_2024-04-15_08-14-29-784x1024.jpg 784w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/04\/photo_2024-04-15_08-14-29-230x300.jpg 230w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/04\/photo_2024-04-15_08-14-29-768x1003.jpg 768w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2024\/04\/photo_2024-04-15_08-14-29.jpg 980w\" sizes=\"auto, (max-width: 784px) 100vw, 784px\" \/><\/figure>\n\n\n\n<p><strong>Sele\u00e7\u00e3o 365Scores da 1\u00aa rodada do Brasileir\u00e3o: Weverton; Hugo, Danilo Barbosa, Gustavo Martins e William; Canobbio, Lima, Ganso e Fernandinho; Vitinho e Borbas; Artur Jorge.<\/strong><\/p>\n\n\n\n<p>O Brasileir\u00e3o retorna j\u00e1 na ter\u00e7a-feira (16), com o jogo entre Bahia e Fluminense, que inicia a rodada do meio de semana. Os jogos ir\u00e3o acontecer at\u00e9 quinta-feira (18). Vale frisar que a <a href=\"https:\/\/www.cbf.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">CBF<\/a> adiou o duelo entre Cuiab\u00e1 e Vit\u00f3ria em virtude da <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/match\/copa-verde-6208\/cuiaba-vila-nova-go-1782-9188-6208#id=4110259\" target=\"_blank\" rel=\"noreferrer noopener\">semifinal da Copa Verde<\/a>.<\/p>\n\n\n\n<p><em><strong>Fique por dentro de <\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>tudo o que acontece no futebol do Brasil e do mundo<\/em><\/strong><\/a><em><strong> acessando o site do 365scores: resultado ao vivo, <\/strong><\/em><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\" target=\"_blank\" rel=\"noreferrer noopener\"><strong><em>jogos de hoje em andamento<\/em><\/strong><\/a><em><strong>, classifica\u00e7\u00e3o atualizada, hist\u00f3rico de confrontos, desfalques e muito mais!<\/strong><\/em><\/p>\n\n\n\n<div\n    data-scores-container-id=\"widgets-samples\"\n    data-widget-type=\"predictions\"\n    data-entity-type=\"league\"\n    data-show-powered-by=\"true\"\n    data-publisher-id=\"2\"\n    data-user-country-id=\"21\"\n    data-entity-id=\"113\"\n    data-show-odds=\"true\"\n    data-show-sponsorship=\"true\"\n    data-enable-impression-count=\"true\"\n    data-allow-insight=\"true\"\n    data-lang=\"pt-BR\">\n<\/div>\n<div\n    id=\"powered-by\">Desenvolvido\n    por<a id=\"powered-by-link\" href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noopener\">365Scores.com\n<\/a>\n<\/div>\n<script\n    src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>O Brasileir\u00e3o 2024 oficialmente come\u00e7ou. Com dez partidas e 28 gols marcados, os 20 principais times do pa\u00eds voltaram \u00e0 a\u00e7\u00e3o em busca do trof\u00e9u mais cobi\u00e7ado do ano. Apesar dos resultados nem t\u00e3o positivos, os cariocas foram os destaques da Time da Rodada 365Scores. Protagonista do primeiro grande jogo no s\u00e1bado (13), o Fluminense &hellip;<\/p>\n","protected":false},"author":25,"featured_media":183865,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1125],"tags":[],"content-tags":[],"class_list":["post-183860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-a"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/183860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=183860"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/183860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/183865"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=183860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=183860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=183860"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=183860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}