{"id":178849,"date":"2024-01-13T13:43:41","date_gmt":"2024-01-13T16:43:41","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=178849"},"modified":"2024-01-13T13:43:44","modified_gmt":"2024-01-13T16:43:44","slug":"botafogo-negocia-com-allan-ex-vasco-e-napoli","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/botafogo-negocia-com-allan-ex-vasco-e-napoli\/","title":{"rendered":"Botafogo negocia com Allan, ex-Vasco e Napoli"},"content":{"rendered":"\n<p>De olho no mercado de transfer\u00eancias, o <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/botafogo-1211\">Botafogo <\/a>est\u00e1 negociando com o volante <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/allan-6252\">Allan<\/a>, jogador revelado pelo <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/vasco-da-gama-1227\">Vasco <\/a>e com passagem pelo <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/napoli-234\">Napoli<\/a>. Atualmente, o atleta tem 33 anos e est\u00e1 no <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/team\/wahda-abu-dhabi-8350\">Al-Wahda<\/a>, dos Emirados \u00c1rabes Unidos.<\/p>\n\n\n\n<p>De acordo com o &#8216;ge&#8217;, o atleta virou alvo visto que a diretoria entendeu que o meio-campo era um setor que precisava ser refor\u00e7ado. Allan, por sua vez, \u00e9 muito bem avaliado internamente e chegaria para ser um camisa 8, disputando posi\u00e7\u00e3o com<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/tche-tche-42227\"> Tch\u00ea Tch\u00ea<\/a> e <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/player\/patrick-de-paula-73218\">Patrick de Paula.<\/a><\/p>\n\n\n\n<p>Ainda segundo as informa\u00e7\u00f5es, as conversas evolu\u00edram nos \u00faltimos dias, mas as equipes e o jogador ainda n\u00e3o possuem acordo. <\/p>\n\n\n\n<p>Allan tem contrato com o Al-Wahda at\u00e9 junho, portanto est\u00e1 livre para assinar um pr\u00e9-contrato com qualquer outro clube e sair de gra\u00e7a. No entanto, o Botafogo desejaria contar com o atleta imediatamente e por isso precisaria do ok do time dos Emirados \u00c1rabes Unidos.<\/p>\n\n\n\n<p><strong><em>O <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/mercado-da-bola-veja-os-principais-rumores-do-brasileirao-serie-a\/\"><strong><em>mercado da bola<\/em><\/strong><\/a><strong><em> est\u00e1 a mil. Visite o site do 365Scores e saiba as <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/brasileirao-serie-a\/league\/113\/transfers\"><strong><em>principais transfer\u00eancias<\/em><\/strong><\/a><strong><em>, rumores, <\/em><\/strong><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/live\"><strong><em>jogos em andamento<\/em><\/strong><\/a><strong><em> pelo mundo, confira a tabela de pontos atualizada de todos os campeonatos, estat\u00edsticas e mais!<\/em><\/strong><\/p>\n\n\n\n<div data-scores-container-id=\"widgets-samples\" data-widget-type=\"predictions\" data-show-powered-by=\"true\" data-lang=\"pt-BR\" data-publisher-id=\"2\" data-user-country-id=\"21\" data-show-odds=\"true\" data-odds-type=\"decimal\" data-show-sponsorship=\"true\" data-enable-impression-count=\"true\" data-allow-insight=\"true\">\n<div id=\"powered-by\"> Desenvolvido por\n<a id=\"powered-by-link\" href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noopener\">365Scores.com <\/a><\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>De olho no mercado de transfer\u00eancias, o Botafogo est\u00e1 negociando com o volante Allan, jogador revelado pelo Vasco e com passagem pelo Napoli. Atualmente, o atleta tem 33 anos e est\u00e1 no Al-Wahda, dos Emirados \u00c1rabes Unidos. De acordo com o &#8216;ge&#8217;, o atleta virou alvo visto que a diretoria entendeu que o meio-campo era &hellip;<\/p>\n","protected":false},"author":2,"featured_media":175031,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1116],"tags":[],"content-tags":[],"class_list":["post-178849","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mercado-da-bola"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/178849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=178849"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/178849\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/175031"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=178849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=178849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=178849"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=178849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}