{"id":164761,"date":"2023-04-30T21:00:28","date_gmt":"2023-05-01T00:00:28","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=164761"},"modified":"2023-04-30T21:12:52","modified_gmt":"2023-05-01T00:12:52","slug":"flamengo-x-vasco-os-maiores-jogos-do-classico","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/flamengo-x-vasco-os-maiores-jogos-do-classico\/","title":{"rendered":"Flamengo x Vasco: Os Maiores Jogos do Cl\u00e1ssico"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/brasileirao-serie-a\/match\/flamengo-vasco-da-gama\/1215-1227-113\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo&nbsp;e&nbsp;Vasco da Gama<\/a>&nbsp;protagonizam&nbsp;um dos maiores cl\u00e1ssicos do futebol brasileiro. Conhecido como Cl\u00e1ssico dos Milh\u00f5es, com quase 400 duelos enfrentados, \u00e9 o mais popular entre os dois clubes na cidade do Rio de Janeiro uma vez que re\u00fane as duas maiores torcidas cariocas e tamb\u00e9m \u00e9 uma das maiores rivalidades futebol\u00edsticas.<\/p>\n\n\n\n<div data-scores-container-id=\"widgets-samples\" data-widget-type=\"predictions\" data-entity-type=\"team\" data-show-powered-by=\"true\" data-publisher-id=\"2\" data-user-country-id=\"21\" data-entity-id=\"1215\" data-show-odds=\"true\" data-show-sponsorship=\"true\" data-enable-impression-count=\"true\" data-allow-insight=\"true\" data-lang=\"pt-BR\">\n<\/div>\n<div id=\"powered-by\">Desenvolvido\n    por<a id=\"powered-by-link\" href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noopener\">365Scores.com\n<\/a>\n<\/div>\n<script src=\"https:\/\/widgets.365scores.com\/main.js\">\n<\/script>\n\n\n\n<p>Depois de um per\u00edodo de empates consecutivos, os \u00faltimos anos foram marcados pela supremacia dos Rubro-Negros, que t\u00eam um retrospecto de muitas vit\u00f3rias de 2019 at\u00e9 hoje. Com isso, n\u00f3s, do 365 Scores, separamos um apanhado geral sobre o retrospecto dos cl\u00e1ssicos, rivalidades, os craques, e claro, a hist\u00f3ria de ambos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hist\u00f3ria dos dois clubes e do confronto direto<\/h2>\n\n\n\n<p>A funda\u00e7\u00e3o do <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/flamengo\/team\/1215\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo<\/a> ocorreu n\u00e3o em fun\u00e7\u00e3o do futebol, mas sim do remo, esporte muito popular no Brasil no final do s\u00e9culo XIX. Fundado em 17 de novembro de 1895 por Jos\u00e9 Agostinho Pereira da Cunha, M\u00e1rio Esp\u00edndola, Augusto de Figueira Lopes e Nestor de Barros que se reuniram para iniciar o projeto do clube. A entrada da equipe no futebol aconteceu apenas em 1912, e desde ent\u00e3o, conquistou diversos t\u00edtulos.<\/p>\n\n\n\n<p>Assim como o Flamengo, o <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/vasco-da-gama\/team\/1227\" target=\"_blank\" rel=\"noreferrer noopener\">Vasco da Gama<\/a>  foi fundado em fun\u00e7\u00e3o da pr\u00e1tica esportiva do remo. Fundado em 1898, na cidade do Rio de Janeiro, o clube ganhou o seu nome em homenagem ao navegador portugu\u00eas Vasco da Gama. As cores escolhidas para simbolizar o clube foram o preto, o branco e o vermelho, estilizados na cruz de malta, s\u00edmbolo do time. No entanto, foi apenas em 1916 que o Vasco passou a integrar o futebol carioca.<\/p>\n\n\n\n<p>Flamengo e Vasco s\u00e3o os \u00fanicos clubes cariocas com status de campe\u00f5es da Am\u00e9rica: o Rubro-Negro sendo tricampe\u00e3o e o Cruz-Maltino bicampe\u00e3o sul-americano. <\/p>\n\n\n\n<p>Sempre quando h\u00e1 confronto direto, o jogo \u00e9 muito quente. At\u00e9 hoje, o Flamengo leva a melhor e j\u00e1 soma 156 vit\u00f3rias&nbsp;contra 132 do&nbsp;Vasco, al\u00e9m de 111 empates. O Rubro-Negro j\u00e1 balan\u00e7ou as redes 543 vezes, enquanto o Cruz-maltino comemorou 513 tentos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Import\u00e2ncia do cl\u00e1ssico para o futebol carioca e brasileiro<\/h2>\n\n\n\n<p>Como muitos imaginam, todo cl\u00e1ssico \u00e9 o melhor que outro. Mas por qu\u00ea disso? Por ser um confronto futebol\u00edstico de grande rivalidade gerada por diversos motivos, as torcidas acreditam que quem vencer \u00e9 o melhor.<\/p>\n\n\n\n<p>O Cl\u00e1ssico dos Milh\u00f5es \u00e9 conhecido pela grande rivalidade das duas maiores torcidas cariocas. Tendo em base a isso, os duelos sempre v\u00e3o causar euforia tanto fora do gramado quanto dentro. Cl\u00e1ssico \u00e9 sempre igual, independente da fase em que os times est\u00e3o. No entanto, por achar que est\u00e1 mal, o outro \u00e9 superior e tem mais chances de vencer. <\/p>\n\n\n\n<p>Outro fator que pesa, \u00e9 a press\u00e3o dos dois lados por ser um confronto direto de grande rivalidade. Se j\u00e1 come\u00e7a antes da partida iniciar, dentro de campo a press\u00e3o multiplica entre os jogadores. Brigas, discuss\u00f5es s\u00e3o normais de se ver. E o melhor, \u00e9 ap\u00f3s o apito final, em que uma das torcidas e jogadores estar\u00e3o mais felizes que os outros.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Os maiores jogos da hist\u00f3ria do cl\u00e1ssico<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Flamengo 4 x 3 Vasco (final do Campeonato Carioca de 2001)<\/h3>\n\n\n\n<p>Conquistado pelo Flamengo, a final do Campeonato Carioca de 2001 ainda \u00e9 lembrada por muitos torcedores at\u00e9 os dias de hoje. Isso porque a decis\u00e3o ficou marcada pelo famoso gol de falta de Petkovic.<\/p>\n\n\n\n<p>O Flamengo conquistou o tricampeonato estadual ao vencer o\u00a0Vasco da Gama\u00a0em duas partidas na final. Na primeira partida, o Cruz-Maltino havia vencido por 2 a 1, mas na segunda partida, o Rubro-Negro conseguiu vencer por 3 a 1, com o gol de\u00a0falta\u00a0do\u00a0meia\u00a0s\u00e9rvio\u00a0Petkovic, quando estava pr\u00f3ximo ao t\u00e9rmino do confronto.<\/p>\n\n\n\n<p>Vale lembrar que o Vasco tinha a vantagem do empate nos dois jogos da decis\u00e3o. Ganhando o primeiro duelo de virada com gols de Viola e Juninho Paulista, tudo se encaminhava para a conquista do campeonato.<\/p>\n\n\n\n<p>J\u00e1 na segunda partida, o Flamengo precisava vencer por dois gols de diferen\u00e7a. No Maracan\u00e3 cheio de torcedores, a equipe rubro-negra abriu o placar e botou fogo no jogo. Ed\u00edlson, de p\u00eanalti, fez o 1 a 0, aos 21 minutos. Juninho Paulista, aos 41 minutos, empatou a partida e o Vasco colocou a m\u00e3o na ta\u00e7a novamente. No segundo tempo, os jogadores do Flamengo foram para cima e de novo o atacante marcou, desta vez de cabe\u00e7a.<\/p>\n\n\n\n<p>Aos 43 minutos do segundo tempo, falta em Ed\u00edlson, na entrada da grande \u00e1rea do Vasco. O s\u00e9rvio Petkovic pegou a bola, ajeitou a batida e entrou para a hist\u00f3ria do Flamengo. Chute forte, no \u00e2ngulo esquerdo do goleiro H\u00e9lton. Com a vit\u00f3ria por 3 x 1, conquistaram o o tricampeonato do Estadual. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-4-3 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Flamengo 3 x 1 Vasco - Campe\u00e3o Carioca 2001\" width=\"500\" height=\"375\" src=\"https:\/\/www.youtube.com\/embed\/NqQtFHtOBqo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Flamengo 1 x 0 Vasco (final do Carioca de 1978)<\/h3>\n\n\n\n<p>Em 1978, com o famoso gol de Rodinelli, o Rubro-Negro conquistou o segundo turno da disputa (Ta\u00e7a Rio de Janeiro, sem liga\u00e7\u00e3o com a atual Ta\u00e7a Rio, esta criada em 1982) e garantiu o trof\u00e9u do estadual daquele ano, o 18\u00ba de sua hist\u00f3ria. H\u00e1 44 anos, o regulamento era bem mais simples: quem vencesse os dois turnos do Carioca era campe\u00e3o autom\u00e1tico, e o Flamengo j\u00e1 tinha vencido a Ta\u00e7a Guanabara.<\/p>\n\n\n\n<p>Na \u00e9poca, o panorama era oposto nos tradicionais rivais cariocas. De um lado, o clube da Colina chegava embalado \u00e0 final do segundo turno, por uma chance de avan\u00e7ar \u00e0 decis\u00e3o geral e levar o bicampeonato. Do outro, um Rubro-Negro em crise: uma seca hist\u00f3rica de gols (cinco jogos sem marcar sobre o Vasco, a maior sequ\u00eancia rubro-negra sem gols no cl\u00e1ssico at\u00e9 hoje) e um vice-campeonato para o rival, al\u00e9m de um tima\u00e7o no papel que n\u00e3o conseguia levantar trof\u00e9us.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Flamengo 2 x 1 Vasco (final do Campeonato Carioca de 1981)<\/h3>\n\n\n\n<p>Por ter vencido dois dos tr\u00eas turnos do estadual de 1981, o Flamengo levantou a ta\u00e7a contra o Vasco da Gama (vencedor do \u00fanico turno) com um simples empate em qualquer uma das duas partidas da final.<\/p>\n\n\n\n<p>O Vasco, portanto, necessitava vencer as 3 partidas. Caso o jogo 3 terminasse empatado, o t\u00edtulo seria decidido nos p\u00eanaltis.<\/p>\n\n\n\n<p>O primeiro jogo o Vasco ganhou de 2 a 0, o segundo por 1 a 0, e o terceiro, o Flamengo conquistou o t\u00edtulo ao ganhar por 2 a 1.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Vasco 5 x 2 Flamengo (Campeonato Carioca de 1949)<\/h3>\n\n\n\n<p>O Vasco da Gama foi o campe\u00e3o carioca de 1949, de maneira invicta, do Campeonato Estadual. O vice-campe\u00e3o foi o Fluminense.<\/p>\n\n\n\n<p>Com um verdadeiro campeonato de Ademir Menezes, artilheiro da competi\u00e7\u00e3o com 31 gols marcados, o Vasco&nbsp;atropelou os rivais, com direito a v\u00e1rias goleadas, inclusive de 5 a 2 para o Flamengo. O ataque cruzmaltino naquele ano marcou 84 gols, em 20 jogos, o que d\u00e1 uma m\u00e9dia de 4,2 por jogo.<\/p>\n\n\n\n<p>No&nbsp;Campeonato de 1949, o Flamengo brigava pela ponta at\u00e9 o final do turno, ali, junto ao Botafogo e Vasco. Ambas as equipes se enfrentaram em S\u00e3o Janu\u00e1rio, no dia 21 de agosto. Exatamente quando o clube da Colina estava comemorando mais um anivers\u00e1rio.<\/p>\n\n\n\n<p>Com apenas dez minutos de jogo, o Flamengo vencia por 2 a 0. Como o Rubro-Negro estava anulando o artilheiro do Vasco, Ademir, o t\u00e9cnico, na \u00e9poca, Fl\u00e1vio Costa recuou o jogador, colocando-o para armar as jogadas, e adiantou o&nbsp;Maneca, como centroavante, no meio dos zagueiros do Flamengo. Danilo&nbsp;diminuiu com um gol esquisito e logo depois Maneca empatava com um chute rasteiro. <\/p>\n\n\n\n<p>O Vasco aplicou a maior goleada em um cl\u00e1ssico contra o Flamengo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Final do Carioca de 1999 &#8211; Flamengo 2 x 1 Vaco<\/h3>\n\n\n\n<p>O&nbsp;Campeonato Carioca de Futebol de 1999&nbsp;teve como campe\u00e3o o Clube de Regatas do Flamengo, vencedor da Ta\u00e7a Guanabara, ao derrotar o Vasco da Gama, vencedor da Ta\u00e7a Rio. A final foi vencida pelo Flamengo por 1 x 0, gol de Rodrigo Mendes, ap\u00f3s empate no primeiro jogo em 1 x 1.<\/p>\n\n\n\n<p>Como havia feito a melhor campanha na competi\u00e7\u00e3o, o Vasco tinha a vantagem do empate no segundo jogo, restava ao Flamengo somente a vit\u00f3ria, que come\u00e7ou aos 31 minutos da segunda etapa.<\/p>\n\n\n\n<p>Na \u00e9poca, o Rubro-Negro, comandado pelo t\u00e9cnico Carlinhos, foi campe\u00e3o com os seguintes jogadores: Cl\u00eamer, F\u00e1bio Baiano, Fab\u00e3o, Luiz Alberto e Athirson; Jorginho, V\u00e1gner (Rodrigo Mendes), Beto e Iranildo (Caio); Leandro (Fabiano) e Rom\u00e1rio.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Vasco 0x1 Flamengo (19\/06\/1999) - Final Carioca 1999 (Flamengo campe\u00e3o)\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/AjR1BgvuHvE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Os craques que marcaram o cl\u00e1ssico<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Zico (Flamengo)<\/h3>\n\n\n\n<p>Aos 70 anos, Zico, o maior \u00eddolo do&nbsp;Flamengo. O eterno camisa 10 da G\u00e1vea \u00e9 o artilheiro rubro-negro no Cl\u00e1ssico dos Milh\u00f5es, com 19 gols marcados.<\/p>\n\n\n\n<p>Sua hist\u00f3ria com o Vasco come\u00e7ou em julho de 1971, no Maracan\u00e3, est\u00e1dio no qual \u00e9 o maior goleador com 333 gols. Na \u00e9poca, aos 18 anos, fez a primeira partida do cl\u00e1ssico e na ocasi\u00e3o, deu uma assist\u00eancia para Nei Oliveira abrir o placar da vit\u00f3ria por 2 a 1 em cima do Vasco.<\/p>\n\n\n\n<p>No entanto, s\u00f3 balan\u00e7ou as redes tr\u00eas cl\u00e1ssicos depois, j\u00e1 em 1973, no empate por 2 a 2, pela 1\u00aa fase do Campeonato Nacional de Clubes. O camisa 10 abriu o placar aos 45 minutos, mas viu Roberto Dinamite empatar. Dad\u00e1 Maravilha marcou para o&nbsp;Flamengo&nbsp;e Alfinete empatou, no \u00faltimo minuto, para o Vasco.<\/p>\n\n\n\n<p>Depois disso, Zico deixou sua marca nos outros quatro cl\u00e1ssicos consecutivos que aconteceram em 1974. Boa parte da rivalidade entre os clubes foi constru\u00edda neste per\u00edodo de grandes disputas comandadas por Zico de um lado e Dinamite do outro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"984\" height=\"482\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2020\/11\/Zico-Reproducao-e1616190096765-1.jpeg\" alt=\"\" class=\"wp-image-46494\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2020\/11\/Zico-Reproducao-e1616190096765-1.jpeg 984w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2020\/11\/Zico-Reproducao-e1616190096765-1-300x147.jpeg 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2020\/11\/Zico-Reproducao-e1616190096765-1-768x376.jpeg 768w\" sizes=\"auto, (max-width: 984px) 100vw, 984px\" \/><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p>Na final do Carioca de 1978, apesar de n\u00e3o ter marcado, teve a participa\u00e7\u00e3o especial dando a assist\u00eancia para Rondinelli fazer o gol do t\u00edtulo. O Maracan\u00e3 foi o palco da decis\u00e3o e, inclusive, Zico aponta este como o jogo mais especial no est\u00e1dio, que foi o in\u00edcio da sequ\u00eancia de conquistas da gera\u00e7\u00e3o campe\u00e3 do mundo em 1981.<\/p>\n\n\n\n<p>Seu \u00faltimo cl\u00e1ssico contra o Vasco aconteceu 18 anos ap\u00f3s a estreia.<\/p>\n\n\n\n<p>Ao todo, o camisa 10 da G\u00e1vea disputou 49 jogos contra o Vasco: 18 vit\u00f3rias, 19 empates e 12 derrotas. Foram 19 gols marcados, sendo o artilheiro rubro-negro do cl\u00e1ssico. Al\u00e9m das nove assist\u00eancias.<\/p>\n\n\n\n<p>A maioria dos cl\u00e1ssicos foi no Campeonato Carioca: 37 dos 49. Zico conquistou cinco t\u00edtulos estaduais em cima do Vasco: 1974, 1978, 1979, 1981 e 1986. O Vasco levou a melhor em quatro ocasi\u00f5es: 1977, 1982, 1987 e 1988.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Rom\u00e1rio (Vasco)<\/h3>\n\n\n\n<p>Desde cedo, Rom\u00e1rio mostrou que seria um personagem da hist\u00f3ria do cl\u00e1ssico. Na primeira passagem pelo Vasco, de 1985 a 1988, fez cinco gols no Flamengo. Dois deles na final da Ta\u00e7a Guanabara de 1986, quando foi o her\u00f3i do t\u00edtulo vasca\u00edno.<\/p>\n\n\n\n<p>Quando veio jogar no Flamengo, em 1995, o Baixinho provocou o Vasco. Declarou ser rubro-negro. Nos cinco anos em que ficou na G\u00e1vea enfrentou o Vasco 12 vezes e fez cinco gols. Um deles na final da Ta\u00e7a Guanabara de 1996, quando o Flamengo se consagrou campe\u00e3o.<\/p>\n\n\n\n<p>Rom\u00e1rio voltou ao Vasco em 1999 com o desafio de reconquistar a torcida. E marcou mais oito gols no rival, mas perdeu as duas finais do Campeonato Carioca que disputou contra o Flamengo.<\/p>\n\n\n\n<p>No total, Rom\u00e1rio j\u00e1 fez 19 gols no Cl\u00e1ssico dos Milh\u00f5es, sendo cinco com a camisa do Flamengo e 14 gols com a do Vasco. Em 2001, o atacante teve atua\u00e7\u00e3o de gala na goleada de 5 a 1 do time da Colina na final da Ta\u00e7a Guanabara.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/210502442_836607977063126_7711747584263359403_n-1-1024x682.jpg\" alt=\"Rom\u00e1rio\" class=\"wp-image-109436\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/210502442_836607977063126_7711747584263359403_n-1-1024x682.jpg 1024w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/210502442_836607977063126_7711747584263359403_n-1-300x200.jpg 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/210502442_836607977063126_7711747584263359403_n-1-768x511.jpg 768w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/210502442_836607977063126_7711747584263359403_n-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Foto: Reprodu\u00e7\u00e3o\/Instagram\/Rom\u00e1rio<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Ad\u00edlio (Flamengo)<\/h3>\n\n\n\n<p>Criado no Flamengo, clube que defendeu por grande parte de sua carreira, Ad\u00edlio atuou ao lado de Zico e Andrade, formando um dos melhores meio-campo da hist\u00f3ria. Com esse time, o Rubro-Negro conquistou suas maiores gl\u00f3rias, incluindo a Ta\u00e7a Libertadores da Am\u00e9rica e o Mundial Interclubes de 1981, al\u00e9m dos Brasileiros de 1980, 1982 e 1983.<\/p>\n\n\n\n<p>Ad\u00edlio era um jogador de rara habilidade e criatividade. Apesar disso, soube ser decisivo em sua carreira, quando marcou o segundo gol do Flamengo na vit\u00f3ria de 3\u00d70 sobre o Liverpool na final do Mundial de Clubes de 1981, ou quando fez o terceiro gol na vit\u00f3ria de 3\u00d70 sobre o Santos na decis\u00e3o do Campeonato Brasileiro de 1983. <\/p>\n\n\n\n<p>Atuou na equipe carioca entre 1975 e 1987, quando teve a oportunidade de vestir a camisa rubro-negra em 616 partidas, o que faz dele o terceiro jogador com maior n\u00famero de jogos disputados pelo Flamengo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Roberto Dinamite (Vasco)<\/h3>\n\n\n\n<p>Roberto Dinamite \u00e9 o maior artilheiro da hist\u00f3ria do Cl\u00e1ssico dos Milh\u00f5es. \u00cdcone do Vasco, o ex-atacante anotou 27 gols contra o Flamengo. O goleador era realmente diferenciado e dificilmente passava em branco no duelo entre os gigantes do Rio.<\/p>\n\n\n\n<p>Al\u00e9m de ser o maior artilheiro do cl\u00e1ssico, ele tamb\u00e9m \u00e9 o maior artilheiro da hist\u00f3ria de todas as edi\u00e7\u00f5es do Campeonato Brasileiro, de Campeonatos Cariocas, e tamb\u00e9m do est\u00e1dio de S\u00e3o Janu\u00e1rio.<\/p>\n\n\n\n<p>Em 1.110 gols pelo Vasco, Dinamite anotou 708 gols. Conquistou um Campeonato Brasileiro (1974) e cinco Campeonatos Cariocas (1977, 1982, 1987, 1988 e 1992). Tamb\u00e9m disputou duas Copas do Mundo (1978 e 1982) e tamb\u00e9m teve breves passagens pela Portuguesa, em 1989, e pelo Campo Grande, em 1991, antes de retornar ao clube do cora\u00e7\u00e3o para encerrar a carreira em fevereiro de 1993 num amistoso entre Vasco e La Coru\u00f1a, da Espanha, no Maracan\u00e3. Naquele dia, Zico, \u00eddolo do rival Flamengo, vestiu a camisa cruz-maltina para homenagear o amigo.<\/p>\n\n\n\n<p>Morreu em janeiro desde ano, aos 68 anos, v\u00edtima de um c\u00e2ncer no intestino no qual vinha lutando desde o fim de 2021.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"667\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/52002099732-9005aae3bf-o.webp\" alt=\"\" class=\"wp-image-164941\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/52002099732-9005aae3bf-o.webp 1000w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/52002099732-9005aae3bf-o-300x200.webp 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/52002099732-9005aae3bf-o-768x512.webp 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption class=\"wp-element-caption\">Foto: Daniel Ramalho\/Vasco<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Andrade (Flamengo)<\/h3>\n\n\n\n<p>Um dos maiores e mais vitoriosos \u00eddolos do Clube de Regatas do Flamengo, Andrade estreou com a camisa rubro-negra em um amistoso em 1976 no qual a equipe derrotou por 2 a 0 a sele\u00e7\u00e3o brasileira, com gols de Paulinho e Luiz Paulo. <\/p>\n\n\n\n<p>Andrade vestiu a camisa rubro-negra por 10 anos: 1977 at\u00e9 1987. Com ela, foram 566 jogos com 329 vit\u00f3rias, 138 empates e 99 derrotas e 28 gols. Transferiu-se para a Roma, da It\u00e1lia, e retornou ao futebol carioca, em 90, para defender o Vasco da Gama.<\/p>\n\n\n\n<p>Ap\u00f3s encerrar sua carreira como jogador, Andrade trabalhou por muitos anos no futebol do Flamengo. Em in\u00fameras ocasi\u00f5es, assim que algum t\u00e9cnico do Flamengo era demitido, Andrade assumia o comando t\u00e9cnico. Foi assim em 2004, quando assumiu ap\u00f3s a queda do t\u00e9cnico Abel Braga e conseguiu evitar o rebaixamento da equipe no Brasileir\u00e3o. E em 2005, quando assumiu logo ap\u00f3s a queda do t\u00e9cnico Celso Roth.<\/p>\n\n\n\n<p>Em julho de 2009, ap\u00f3s a sa\u00edda do t\u00e9cnico Cuca, voltou a assumir o Flamengo, primeiro de maneira interina e depois como treinador efetivo. Ap\u00f3s perder o t\u00edtulo da Ta\u00e7a Rio para o Botafogo, que foi Campe\u00e3o Carioca pois j\u00e1 havia vencido a Ta\u00e7a Guanabara, Andrade tamb\u00e9m foi contestado na campanha da Libertadores, com altos e baixos, o que culminou com sua demiss\u00e3o, em 23 de abril de 2010.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"901\" height=\"600\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/andrade-paula-reis-flamengo.webp\" alt=\"\" class=\"wp-image-164943\" srcset=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/andrade-paula-reis-flamengo.webp 901w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/andrade-paula-reis-flamengo-300x200.webp 300w, https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2023\/04\/andrade-paula-reis-flamengo-768x511.webp 768w\" sizes=\"auto, (max-width: 901px) 100vw, 901px\" \/><figcaption class=\"wp-element-caption\">Foto: Paula Reis\/Flamengo<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">A rivalidade entre as torcidas<\/h2>\n\n\n\n<p>A enorme rivalidade come\u00e7ou nas \u00e1guas&nbsp;da Ba\u00eda de Guanabara, quando o remo era o esporte mais popular. No total s\u00e3o 47 t\u00edtulos para o Flamengo e 46 t\u00edtulos para o Vasco. Nos campos de futebol, o duelo nasceu s\u00f3 em 1912, quando o Rubro-Negro criou um time com jogadores que abandonaram o Fluminense. J\u00e1 o Cruz-Maltino,&nbsp;estreou oficialmente no futebol em 1916, na terceira divis\u00e3o, ap\u00f3s a fus\u00e3o no ano anterior de clubes ligados \u00e0 col\u00f4nia portuguesa do Rio de Janeiro.<\/p>\n\n\n\n<p>No entanto, essa rivalidade no futebol esquentou mesmo em 1923, quando finalmente o Vasco chegou \u00e0 primeira divis\u00e3o. Logo em seu ano de estreia, ganhou o Campeonato Carioca com uma campanha arrasadora e que perdeu apenas 1 jogo, justamente contra o Flamengo. Naquela altura o Rubro-Negro j\u00e1 tinha 4 t\u00edtulos cariocas.<\/p>\n\n\n\n<p>Ao longo dos anos, as duas equipes come\u00e7aram a colecionar t\u00edtulos e protagonizarem disputas acirradas: foram quase 400 partidas, sendo 156 vit\u00f3rias rubro-negras, 132 vit\u00f3rias cruzmaltinas e 111 empates. Al\u00e9m disso, as equipes tiveram em 22 disputas diretas de Campeonato Cariocas. Foram 12 t\u00edtulos para a G\u00e1vea e 10 para S\u00e3o Janu\u00e1rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O clima nas arquibancadas durante o cl\u00e1ssico<\/h3>\n\n\n\n<p>O clima nas arquibancadas come\u00e7a bem antes do cl\u00e1ssico come\u00e7ar. Na maioria das vezes, os torcedores de ambas as equipes, j\u00e1 come\u00e7am a festa no lado de fora do est\u00e1dio com recep\u00e7\u00e3o ao \u00f4nibus, fogos, sinalizadores. No entanto, muitas das festas do pr\u00e9-jogo \u00e9 marcado por confus\u00f5es e mortes.<\/p>\n\n\n\n<p>O Cl\u00e1ssico dos Milh\u00f5es \u00e9 marcado por muitas brigas dentro e fora dos est\u00e1dios. Al\u00e9m disso, como o clima \u00e9 quente, at\u00e9 os jogadores discutem entre si e rolam aquela pequena discuss\u00e3o. Na maioria das vezes, as confus\u00f5es s\u00e3o separadas pelos policiais que jogam bomba, g\u00e1s de pimenta para dispersar a multid\u00e3o.<\/p>\n\n\n\n<p>Por um lado, a cena \u00e9 totalmente triste, mas por outro, ainda tem a festa bonita que os torcedores fazem para seus jogadores.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hist\u00f3rias de confrontos entre as torcidas<\/h3>\n\n\n\n<p>Um jogo como&nbsp;Flamengo e Vasco&nbsp;\u00e9 capaz de despertar o melhor e o pior das pessoas. Apesar do est\u00e1dio viver uma noite m\u00e1gica, com direito a recorde de p\u00fablico, duelo de apoio entre as torcidas, uma atmosfera como h\u00e1 muito n\u00e3o era vista no Cl\u00e1ssico dos Milh\u00f5es. Mas do lado de fora,&nbsp;a guerra entre torcedores rivais deixam dezenas de feridos, alguns com gravidade.<\/p>\n\n\n\n<p>Na esperan\u00e7a de jogos menos desiguais entre os dois advers\u00e1rios hist\u00f3ricos, rubro-negros e vasca\u00ednos saem de casa prontos para uma verdadeira batalha.<\/p>\n\n\n\n<p>De um lado, torcedores de ambos os times lotam o Maracan\u00e3 e por outro, encontram o advers\u00e1rio nas arquibancadas disposto a igualar no barulho. Sempre h\u00e1 aqueles f\u00e3s do Flamengo  provocando os rivais, cantando que o time vai voltar a jogar a segunda divis\u00e3o. J\u00e1 os Cruz-maltinos devolvem a provoca\u00e7\u00e3o, dizendo que os flamenguistas n\u00e3o t\u00eam est\u00e1dio, ou que o Maracan\u00e3 \u00e9 deles.<\/p>\n\n\n\n<p>No entanto, o mesmo cl\u00e1ssico que escreve tantas hist\u00f3rias de alegrias e decep\u00e7\u00f5es no futebol \u00e9 estopim para conflitos entre torcedores. Eles ocorreram em diversos pontos da Regi\u00e3o Metropolitana. Os focos maiores s\u00e3o nos arredores do est\u00e1dio. Nas ruas do Maracan\u00e3 e de S\u00e3o Crist\u00f3v\u00e3o, al\u00e9m das esta\u00e7\u00f5es de trem e metr\u00f4 mais pr\u00f3ximas ao est\u00e1dio, diversas brigas eclodem, com muita viol\u00eancia.<\/p>\n\n\n\n<p>A \u00faltima confus\u00e3o que ocorreu, foi na semifinal do Carioca em que um torcedor vasca\u00edno foi espancado e veio a \u00f3bito. Al\u00e9m disso, outros pontos da cidade, foram alvos de conflitos entre os rivais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como a rivalidade se mant\u00e9m viva at\u00e9 os dias de hoje?<\/h2>\n\n\n\n<p>O ato de torcer, que deveria ser uma maneira de inserir o cidad\u00e3o como membro atuante no esporte, tem perdido sua capacidade original, fazendo da modalidade uma v\u00e1lvula de hostilidade e intoler\u00e2ncia. Segundo o Estatuto do Torcedor, o futebol deveria ser uma &#8220;manifesta\u00e7\u00e3o festiva e amig\u00e1vel&#8221;.<\/p>\n\n\n\n<p>Como a&nbsp;viol\u00eancia&nbsp;vem aumentando, torcer dentro do est\u00e1dio fica cada dia mais dif\u00edcil a ponto que passou a impedir duas torcidas de dividirem as arquibancadas, como acontece em muitos estados brasileiros, em que o visitante recebe uma cota \u00ednfima de ingressos. <\/p>\n\n\n\n<p>A viol\u00eancia tamb\u00e9m se manifesta na atmosfera de \u00f3dio que cerca o futebol, por meio de ofensas, posturas desumanas, xingamento. Neste cen\u00e1rio de dificuldades, de maior visibilidade do esporte, com as redes sociais, as in\u00fameras transmiss\u00f5es de jogos e o aumento da press\u00e3o sobre t\u00e9cnicos e jogadores, muitos torcedores passaram a ver o futebol como uma esp\u00e9cie de &#8220;vale-tudo&#8221;. Em vez de o considerarem uma distra\u00e7\u00e3o, um entretenimento, uma forma de integra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m disso, outro fator que contribui para a rivalidade s\u00e3o as empresas patrocinadoras. Elas j\u00e1 esperam que ser\u00e3o criticadas por parte da torcida advers\u00e1ria.<\/p>\n\n\n\n<p>Quer saber de tudo o que acontece no<strong>&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/flamengo\/team\/1215\" target=\"_blank\" rel=\"noreferrer noopener\">Flamengo<\/a> e <a href=\"https:\/\/www.365scores.com\/pt-br\/football\/brazil\/vasco-da-gama\/team\/1227\" target=\"_blank\" rel=\"noreferrer noopener\">Vasco<\/a><\/strong>? Acesse o site do&nbsp;<a href=\"https:\/\/www.365scores.com\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">365scores.com<\/a>&nbsp;e fique por dentro dos jogos em andamento, jogos de hoje, tabela de pontos, classifica\u00e7\u00e3o e muito mais!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Flamengo&nbsp;e&nbsp;Vasco da Gama&nbsp;protagonizam&nbsp;um dos maiores cl\u00e1ssicos do futebol brasileiro. Conhecido como Cl\u00e1ssico dos Milh\u00f5es, com quase 400 duelos enfrentados, \u00e9 o mais popular entre os dois clubes na cidade do Rio de Janeiro uma vez que re\u00fane as duas maiores torcidas cariocas e tamb\u00e9m \u00e9 uma das maiores rivalidades futebol\u00edsticas. Desenvolvido por365Scores.com Depois de um &hellip;<\/p>\n","protected":false},"author":2,"featured_media":164964,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1125],"tags":[],"content-tags":[],"class_list":["post-164761","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","category-brasileiro-serie-a"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/164761","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=164761"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/164761\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/164964"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=164761"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=164761"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=164761"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=164761"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}