{"id":142905,"date":"2022-03-12T18:50:03","date_gmt":"2022-03-12T21:50:03","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=142905"},"modified":"2022-03-12T18:54:21","modified_gmt":"2022-03-12T21:54:21","slug":"apos-vitoria-gremio-e-inter-se-enfrentarao-na-semifinal-do-gauchao","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/apos-vitoria-gremio-e-inter-se-enfrentarao-na-semifinal-do-gauchao\/","title":{"rendered":"Gre-Nal 436: Gr\u00eamio e Inter se enfrentar\u00e3o na semifinal do Gauch\u00e3o"},"content":{"rendered":"\n<p>Ap\u00f3s se enfrentarem no dia 9 de mar\u00e7o no cl\u00e1ssico remarcado, Gr\u00eamio e Internacional se encontrar\u00e3o mais uma vez no Campeonato Ga\u00facho. O Tricolor venceu o Ypiranga por 2 a 0, enquanto o Inter empatou com o Guarany de Bag\u00e9. No entanto, os dois times garantiram a vaga \u00e0 semifinal do estadual. <\/p>\n\n\n\n<p>No \u00faltimo encontro, na primeira fase do campeonato, os colorados sa\u00edram vencedores com gol de David. O primeiro cl\u00e1ssico da semifinal ser\u00e1 no Beira-Rio, e a decis\u00e3o ocorrer\u00e1 na Arena do Gr\u00eamio. O Inter garantiu a classifica\u00e7\u00e3o ap\u00f3s somar 19 pontos e ficar em terceiro lugar. J\u00e1 o rival, ficou em segundo, com 21 pontos.<\/p>\n\n\n\n<p>A outra semifinal ser\u00e1 entre Ypiranga, primeiro colocado do Gauch\u00e3o com 21 pontos, e Brasil de Pelotas, na quarta coloca\u00e7\u00e3o com 16 pontos. As decis\u00f5es acontecer\u00e3o no pr\u00f3ximo s\u00e1bado, dia 19, ou no domingo, dia 20, e na quarta-feira seguinte, dia 23. A Federa\u00e7\u00e3o Ga\u00facha de Futebol ainda n\u00e3o confirmou as datas.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"pt\" dir=\"ltr\">\u26bd Semifinais definidas! <br><br>Confira os duelos da pr\u00f3xima fase do Gauch\u00e3o 2022:<a href=\"https:\/\/twitter.com\/ypirangafc?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@ypirangafc<\/a> x <a href=\"https:\/\/twitter.com\/GEBrasilOficial?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@GEBrasilOficial<\/a> <a href=\"https:\/\/twitter.com\/Gremio?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@Gremio<\/a> x <a href=\"https:\/\/twitter.com\/SCInternacional?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">@SCInternacional<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FGF?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#FGF<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FutebolGa%C3%BAcho?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#FutebolGa\u00facho<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Gauch%C3%A3o2022?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#Gauch\u00e3o2022<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/GrandesHist%C3%B3riasPassamPorAqui?src=hash&amp;ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">#GrandesHist\u00f3riasPassamPorAqui<\/a> <a href=\"https:\/\/t.co\/L9e07l2G6B\">pic.twitter.com\/L9e07l2G6B<\/a><\/p>&mdash; Federa\u00e7\u00e3o Ga\u00facha de Futebol (@OficialFGF) <a href=\"https:\/\/twitter.com\/OficialFGF\/status\/1502763817771622404?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">March 12, 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s se enfrentarem no dia 9 de mar\u00e7o no cl\u00e1ssico remarcado, Gr\u00eamio e Internacional se encontrar\u00e3o mais uma vez no Campeonato Ga\u00facho. O Tricolor venceu o Ypiranga por 2 a 0, enquanto o Inter empatou com o Guarany de Bag\u00e9. No entanto, os dois times garantiram a vaga \u00e0 semifinal do estadual. No \u00faltimo encontro, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":142906,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1160,7],"tags":[1150],"content-tags":[],"class_list":["post-142905","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estaduais","category-futebol","tag-urgente"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/142905","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=142905"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/142905\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/142906"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=142905"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=142905"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=142905"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=142905"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}