{"id":113051,"date":"2021-07-27T09:21:05","date_gmt":"2021-07-27T12:21:05","guid":{"rendered":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/?p=113051"},"modified":"2024-07-04T06:39:58","modified_gmt":"2024-07-04T09:39:58","slug":"torcedores-brasileiros-vao-a-loucura-apos-polemicas-derrotas-de-gabriel-medina-veja-as-reacoes","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/torcedores-brasileiros-vao-a-loucura-apos-polemicas-derrotas-de-gabriel-medina-veja-as-reacoes\/","title":{"rendered":"Torcedores brasileiros v\u00e3o \u00e0 loucura ap\u00f3s derrota de Gabriel Medina; veja as rea\u00e7\u00f5es"},"content":{"rendered":"<p>A derrota do surfista Gabriel Medina na madrugada desta ter\u00e7a-feira (27) deixou os torcedores brasileiros enfurecidos. O bicampe\u00e3o mundial foi superado na semifinal pelo japon\u00eas Kanoa Igarashi e as notas do competidor anfitri\u00e3o foram motivo de muito assunto nas redes sociais.<\/p>\n<p>Para agravar a situa\u00e7\u00e3o, Medina foi derrotado pelo australiano Owen Wright na disputa pelo bronze em nova decis\u00e3o pol\u00eamica, o que revoltou ainda mais a torcida brasileira. Confira alguns coment\u00e1rios e memes sobre o assunto.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">Japon\u00eas com a m\u00e3o apoiado na prancha: 9,33<\/p>\n<p>Gabriel Medina: 8,43 <a href=\"https:\/\/t.co\/mNTdU3DK7D\">pic.twitter.com\/mNTdU3DK7D<\/a><\/p>\n<p>&mdash; Dona L\u00facia (@DonaLuciaHexa) <a href=\"https:\/\/twitter.com\/DonaLuciaHexa\/status\/1419987693770002433?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/barcelona-e-neymar-chegam-a-acordo-amigavel-e-encerram-disputa-judicial\/\"><br \/>\n<img decoding=\"async\" width=\"537\" height=\"307\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/GettyImages-476345932-e1627302469374-1.jpg?crop=1\" alt=\"\" loading=\"lazy\" \/>    <\/a><br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/barcelona-e-neymar-chegam-a-acordo-amigavel-e-encerram-disputa-judicial\/\"><small>Barcelona e Neymar chegam a acordo amig\u00e1vel e encerram disputa judicial<\/small><\/a><\/p>\n<p>Quatro anos depois do neg\u00f3cio que levou Neymar ao Paris Saint-Germain, o brasileiro e o Barcelona chegaram a um acordo &#8230;<\/p>\n<p><a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/richarlison-e-matheus-cunha-posam-com-camisa-do-vasco-ao-lado-de-douglas-luiz-paulinho-ricardo-graca-e-lucao\/\"><br \/>\n<img decoding=\"async\" width=\"100%\" height=\"\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/d97e0fc6-88d0-4cf3-a17f-4423ad7e1cff-e1627307759272-1.jpg?crop=1\" alt=\"\" loading=\"lazy\" \/>    <\/a><br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/richarlison-e-matheus-cunha-posam-com-camisa-do-vasco-ao-lado-de-douglas-luiz-paulinho-ricardo-graca-e-lucao\/\">Richarlison e Matheus Cunha posam com camisa do Vasco ao lado de Douglas Luiz, Paulinho, Ricardo Gra\u00e7a e Luc\u00e3o<\/a><br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/author\/magazine365scores\/\">365Scores<\/a><br \/>\njulho 26, 2021<br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/boletim-olimpico-rayssa-leal-garante-a-terceira-medalha-do-brasil-e-volei-masculino-consegue-virada-historica\/\"><br \/>\n<img decoding=\"async\" width=\"100%\" height=\"\" src=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-content\/uploads\/2021\/07\/GettyImages-1234200664-e1627310303729-1.jpg?crop=1\" alt=\"\" loading=\"lazy\" \/>    <\/a><br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/2021\/07\/26\/boletim-olimpico-rayssa-leal-garante-a-terceira-medalha-do-brasil-e-volei-masculino-consegue-virada-historica\/\">Boletim Ol\u00edmpico: Rayssa Leal garante a terceira medalha do Brasil e v\u00f4lei masculino consegue virada hist\u00f3rica<\/a><br \/>\n<a href=\"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/author\/magazine365scores\/\">365Scores<\/a><br \/>\njulho 26, 2021<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">t\u00f4 assim depois do medina ter sido roubado  <a href=\"https:\/\/t.co\/UDH20D9jx2\">pic.twitter.com\/UDH20D9jx2<\/a><\/p>\n<p>&mdash; mary the eras 25\/11 (@katebridgs) <a href=\"https:\/\/twitter.com\/katebridgs\/status\/1419929732825686034?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>https:\/\/twitter.com\/Omeletwithjam\/status\/1419986908697006095<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">O Medina lan\u00e7a um a\u00e9reo \ud83d\ude4c\ud83c\udffc\ud83c\udfc4\u200d\u2642\ufe0f<\/p>\n<p>Ju\u00edzes do Jap\u00e3o dando a nota \ud83d\ude4c\ud83c\udffc<br \/>Nota 6 ???? <a href=\"https:\/\/t.co\/2483x7jJNz\">pic.twitter.com\/2483x7jJNz<\/a><\/p>\n<p>&mdash; Igooor (@SolarthIgor) <a href=\"https:\/\/twitter.com\/SolarthIgor\/status\/1419900090832113677?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"pt\" dir=\"ltr\">Por que Gabriel Medina foi roubado:<\/p>\n<p>Manobra do japa:<br \/>-m\u00e3o na borda<br \/>-base aberta<br \/>-rabeta da prancha baixa durante o a\u00e9reo<\/p>\n<p>Manobra do Gabi<br \/>-sem m\u00e3o na borda<br \/>-base fixa<br \/>-rabeta quase na vertical<br \/>-foi mais alto<\/p>\n<p>foi um dos roubos mais rid\u00edculos q eu ja vi em todos os esportes <a href=\"https:\/\/t.co\/Vb9RXxnSwJ\">pic.twitter.com\/Vb9RXxnSwJ<\/a><\/p>\n<p>&mdash; \u239b\u239d william \u23a0\u239e (@BaiucaDoPastel) <a href=\"https:\/\/twitter.com\/BaiucaDoPastel\/status\/1419992050125185024?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">July 27, 2021<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p>Foto: Reprodu\u00e7\u00e3o\/Getty Images<\/p>\n<h4>\n<h4 style=\"font-variant-ligatures: normal; font-variant-caps: normal; white-space: normal;\">Siga nas redes sociais<\/h4>\n<\/h4>\n<p><a href=\"https:\/\/www.facebook.com\/365Scores.Brasil\" target=\"_blank\" rel=\"noopener\"><br \/>\nFacebook-f<br \/>\n<\/a><br \/>\n<a href=\"https:\/\/twitter.com\/365Scores_pt\" target=\"_blank\" rel=\"noopener\"><br \/>\nTwitter<br \/>\n<\/a><br \/>\n<a href=\"https:\/\/www.instagram.com\/365scoresbra\/\" target=\"_blank\" rel=\"noopener\"><br \/>\nInstagram<br \/>\n<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A derrota do surfista Gabriel Medina na madrugada desta ter\u00e7a-feira (27) deixou os torcedores brasileiros enfurecidos. O bicampe\u00e3o mundial foi superado na semifinal pelo japon\u00eas Kanoa Igarashi e as notas do competidor anfitri\u00e3o foram motivo de muito assunto nas redes sociais. Para agravar a situa\u00e7\u00e3o, Medina foi derrotado pelo australiano Owen Wright na disputa pelo &hellip;<\/p>\n","protected":false},"author":2,"featured_media":113059,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[1334],"content-tags":[],"class_list":["post-113051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futebol","tag-gabriel-medina"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/113051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/comments?post=113051"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/posts\/113051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media\/113059"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/media?parent=113051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/categories?post=113051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/tags?post=113051"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/pt-br\/news\/magazine\/wp-json\/wp\/v2\/content-tags?post=113051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}