{"id":69385,"date":"2025-08-30T18:05:50","date_gmt":"2025-08-30T21:05:50","guid":{"rendered":"https:\/\/www.365scores.com\/es\/news\/?p=69385"},"modified":"2025-08-30T18:05:53","modified_gmt":"2025-08-30T21:05:53","slug":"colo-colo-vs-universidad-de-chile-historial","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/es\/news\/colo-colo-vs-universidad-de-chile-historial\/","title":{"rendered":"El historial de Colo Colo vs Universidad de Chile: n\u00fameros, rachas y estad\u00edsticas del supercl\u00e1sico chileno"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.365scores.com\/es\/football\/match\/first-division-135\/colo-colo-universidad-de-chile-1239-8541-135#id=4360366\" data-type=\"link\" data-id=\"https:\/\/www.365scores.com\/es\/football\/match\/first-division-135\/colo-colo-universidad-de-chile-1239-8541-135#id=4360366\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Colo Colo<\/strong> vs  <strong>Universidad de Chile<\/strong><\/a> se enfrentan este domingo en el <strong>Estadio Monumental<\/strong> por la edici\u00f3n 198 de este Supercl\u00e1sico, y, como siempre, la emoci\u00f3n estar\u00e1 garantizada. El f\u00fatbol chileno espera otro cap\u00edtulo memorable de esta rivalidad que nunca deja de sorprender. <a href=\"https:\/\/promo.bwin.co\/es\/promo\/p\/sports\/bono-bienvenida?trackerId=5459066&amp;tdpeh=Platform-Web_Context-Magazine_Offer-CTABox_Country-Colombia&amp;btag=301645\" rel=\"noopener\">\u00bfQui\u00e9n ganar\u00e1?<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Colo Colo vs Universidad de Chile: historia de la rivalidad<\/h2>\n\n\n\n<p>Fundados en la primera mitad del siglo XX, <strong>Colo Colo<\/strong> (1925) y <strong>Universidad de Chile<\/strong> (1927) han protagonizado una de las rivalidades m\u00e1s intensas y populares del f\u00fatbol mundial. <\/p>\n\n\n\n<p>Colo Colo, tradicionalmente considerado el equipo del pueblo, tiene una fuerte conexi\u00f3n con las clases populares, mientras que la <strong>U<\/strong>, hist\u00f3ricamente vinculado con la \u00e9lite, es reconocido por su identidad acad\u00e9mica y su gran hinchada. <\/p>\n\n\n\n<p>A lo largo de los a\u00f1os, ambos equipos han sido los principales exponentes del f\u00fatbol chileno, y cada uno ha vivido su propia gloria y sus periodos de dificultades, siempre con la rivalidad como un hilo conductor.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"766\" src=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-1024x766.jpg\" alt=\"\" class=\"wp-image-69683\" srcset=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-1024x766.jpg 1024w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-300x224.jpg 300w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-768x574.jpg 768w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-1536x1149.jpg 1536w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-187578268-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(Foto: Getty Images)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Estad\u00edsticas de Colo Colo vs Universidad de Chile: \u00bfQui\u00e9n domina el historial?<\/h2>\n\n\n\n<p>Hasta el d\u00eda de hoy, los <strong>Supercl\u00e1sicos<\/strong> han sido numerosos. En total, se han jugado <strong>197 partidos de Primera Divisi\u00f3n<\/strong> entre ambos equipos, y en este balance, <strong>Colo Colo<\/strong> mantiene una ligera ventaja sobre <strong>Universidad de Chile<\/strong>. Las estad\u00edsticas indican lo siguiente:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Partidos jugados<\/strong>: 197<\/li>\n\n\n\n<li><strong>Victorias de Colo Colo<\/strong>: 89<\/li>\n\n\n\n<li><strong>Victorias de Universidad de Chile<\/strong>: 50<\/li>\n\n\n\n<li><strong>Empates<\/strong>: 58<\/li>\n\n\n\n<li><strong>Goles a favor de Colo Colo<\/strong>: 331<\/li>\n\n\n\n<li><strong>Goles a favor de Universidad de Chile<\/strong>: 243<\/li>\n<\/ul>\n\n\n\n<p>Esta supremac\u00eda en victorias y goles pone a <strong>Colo Colo<\/strong> como el l\u00edder en esta hist\u00f3rica rivalidad, aunque el equipo de la <strong>U<\/strong> ha logrado importantes triunfos, sobre todo en \u00e9pocas cruciales, lo que mantiene viva la pasi\u00f3n de este enfrentamiento.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2230445033-1024x683.jpg\" alt=\"\" class=\"wp-image-69680\"\/><figcaption class=\"wp-element-caption\">Universidad de Chile va por otra victoria ante Colo Colo (Foto: Getty Images)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Colo Colo vs Universidad de Chile: goleadores y jugadores que marcaron la historia del cl\u00e1sico<\/h2>\n\n\n\n<p>Los nombres que han quedado grabados en la historia del Supercl\u00e1sico entre Colo Colo vs Universidad de Chile son muchos, pero hay dos figuras que destacan como los m\u00e1ximos goleadores de este duelo: <strong>Esteban Paredes<\/strong> (Colo Colo) y <strong>Carlos Campos<\/strong> (Universidad de Chile), quienes comparten el t\u00edtulo de m\u00e1ximos artilleros, con <strong>16 goles<\/strong> cada uno.<\/p>\n\n\n\n<p>En cuanto a los jugadores m\u00e1s representativos, el <strong>portero Misael Escuti<\/strong> es el futbolista con m\u00e1s presencias en Supercl\u00e1sicos, con un total de <strong>37 partidos<\/strong> disputados, consolid\u00e1ndose como un \u00edcono dentro de la historia de estos enfrentamientos. Su legado no solo se mide en atajadas, sino tambi\u00e9n en el simbolismo que tuvo para ambas hinchadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-1024x683.jpg\" alt=\"Arturo Vidal - Colo Colo\" class=\"wp-image-69677\" srcset=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-1024x683.jpg 1024w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-300x200.jpg 300w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-768x512.jpg 768w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-1536x1024.jpg 1536w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2025\/08\/GettyImages-2213222456-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Colo Colo hoy: pron\u00f3sticos de resultado vs Everton en la Liga de Primera de Chile. (Getty Images)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00daltimo Colo Colo vs Universidad de Chile: \u00bfqui\u00e9n gan\u00f3 el supercl\u00e1sico?<\/h2>\n\n\n\n<p>El \u00faltimo <strong>Supercl\u00e1sico<\/strong> se jug\u00f3 el <strong>12 de julio de 2025<\/strong> en el <strong>Estadio Nacional de \u00d1u\u00f1oa<\/strong>, donde <strong>Universidad de Chile<\/strong> logr\u00f3 una victoria de <strong>2-1<\/strong> ante <strong>Colo Colo<\/strong>. Este triunfo fue de gran importancia para el equipo de la <strong>U<\/strong>, ya que puso fin a una racha de <strong>12 a\u00f1os sin derrotar al Cacique en duelos de Primera Divisi\u00f3n<\/strong> en calidad de local. <\/p>\n\n\n\n<p>El resultado fue un alivio para la hinchada azul, que hab\u00eda visto c\u00f3mo el <strong>Popular<\/strong> dominaba en las \u00faltimas ediciones de este cl\u00e1sico jugado en Santiago. La <strong>U<\/strong> logr\u00f3 sus goles gracias a las actuaciones destacadas de <strong>\u00c1ngelo Henr\u00edquez<\/strong> y <strong>Cristi\u00e1n Palacios<\/strong>, mientras que <strong>Colo Colo<\/strong> descont\u00f3 mediante un tanto de <strong>Gabriel Costa<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"TNT Sports Replay | Universidad de Chile 2 - 1 Colo Colo | Fecha 7\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/A37LDoPVOGE?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Colo Colo vs Universidad de Chile se enfrentan este domingo en el Estadio Monumental por la edici\u00f3n 198 de este Supercl\u00e1sico, y, como siempre, la emoci\u00f3n estar\u00e1 garantizada. El f\u00fatbol chileno espera otro cap\u00edtulo memorable de esta rivalidad que nunca deja de sorprender. \u00bfQui\u00e9n ganar\u00e1? Colo Colo vs Universidad de Chile: historia de la rivalidad &hellip;<\/p>\n","protected":false},"author":25,"featured_media":69664,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,34,37],"tags":[4088],"content-tags":[3999,4001,3997],"class_list":["post-69385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-futbol","category-futbol-chileno","category-futbol-latinoamericano","tag-colo-colo-noticias","content-tags-career-history","content-tags-pre-game","content-tags-stats-data","article_type-discover","entity_type-match","inspiration-planned"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts\/69385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/comments?post=69385"}],"version-history":[{"count":5,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts\/69385\/revisions"}],"predecessor-version":[{"id":69685,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts\/69385\/revisions\/69685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/media\/69664"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/media?parent=69385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/categories?post=69385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/tags?post=69385"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/content-tags?post=69385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}