{"id":28521,"date":"2024-09-12T18:18:46","date_gmt":"2024-09-12T18:18:46","guid":{"rendered":"https:\/\/www.365scores.com\/es\/news\/?p=28521"},"modified":"2024-09-12T18:18:48","modified_gmt":"2024-09-12T18:18:48","slug":"julian-alvarez-elogios-koke-capitan","status":"publish","type":"post","link":"https:\/\/www.365scores.com\/es\/news\/julian-alvarez-elogios-koke-capitan\/","title":{"rendered":"Koke llen\u00f3 de elogios a Juli\u00e1n \u00c1lvarez y se mostr\u00f3 feliz por su llegada al Atl\u00e9tico Madrid"},"content":{"rendered":"\n<p><strong>En su vuelta a los entrenamientos al Atl\u00e9tico Madrid, Juli\u00e1n \u00c1lvarez<\/strong>, que podr\u00eda llegar a ser suplente ante Valencia el domingo 15\/9 pensando en el debut en la Champions League ante Leipzig el jueves 19\/9 en el C\u00edvitas Metropolitano, <strong>recibi\u00f3 muchos elogios y el apoyo del capit\u00e1n y uno de los referentes del equipo: Koke Resurrecci\u00f3n.<\/strong><\/p>\n\n\n\n<p><strong>En 365Scores te contamos todo<\/strong>&nbsp;lo que ten\u00e9s que saber de&nbsp;<a href=\"https:\/\/www.365scores.com\/es\/football\/player\/julian-alvarez-61973\">Juli\u00e1n \u00c1lvarez<\/a>&nbsp;y&nbsp;los elogios que recibi\u00f3 por parte del capit\u00e1n del Atl\u00e9tico Madrid.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-1024x683.jpg\" alt=\"Juli\u00e1n \u00c1lvarez Atl\u00e9tico Madrid\" class=\"wp-image-27764\" srcset=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-1024x683.jpg 1024w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-300x200.jpg 300w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-768x512.jpg 768w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-1536x1024.jpg 1536w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/09\/GettyImages-2169620926-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(Photo by Ion Alcoba Beitia\/Getty Images)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Los elogios de Koke, capit\u00e1n del Atl\u00e9tico Madrid, a Juli\u00e1n \u00c1lvarez:<\/h2>\n\n\n\n<p><strong>Koke Resurrecci\u00f3n, capit\u00e1n del Atl\u00e9tico Madrid<\/strong>, se mostr\u00f3 feliz por el mercado de pases que hizo el Colchonero y por la incorporaci\u00f3n estrella de Juli\u00e1n \u00c1lvarez: <em>\u201cFue un mercado muy bueno para el club, que hizo un esfuerzo muy grande.&nbsp;<strong>Fich\u00f3 a un campe\u00f3n del mundo como Juli\u00e1n que se est\u00e1 adaptando, porque no es f\u00e1cil venir de la liga inglesa a la espa\u00f1ola<\/strong>&#8220;.<\/em><\/p>\n\n\n\n<p><strong>Y luego cerr\u00f3 pidiendo que le &#8220;den tiempo&#8221; a la Ara\u00f1a<\/strong>, quien todav\u00eda no logr\u00f3 marcar en los cuatro partidos que lleva disputados con el Atleti: <em>&#8220;Poco a poco ir\u00e1 entendiendo los movimientos que pide el entrenador y&nbsp;<strong>m\u00e1s pronto que tarde vamos a ver la mejor versi\u00f3n de Juli\u00e1n<\/strong>. <strong>Demostr\u00f3 que tiene calidad y hay que darle tiempo<\/strong> porque viene de jugar Copa Am\u00e9rica y los Juegos Ol\u00edmpicos. <\/em><strong><em>Le va a dar muchas alegr\u00edas al Atl\u00e9tico de Madrid\u201d<\/em>.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-1024x683.jpg\" alt=\"Juli\u00e1n \u00c1lvarez Atl\u00e9tico Madrid\" class=\"wp-image-27511\" srcset=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-1024x683.jpg 1024w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-300x200.jpg 300w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-768x512.jpg 768w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-1536x1024.jpg 1536w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168124609-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">(Photo by Jose Breton\/Pics Action\/NurPhoto via Getty Images)<\/figcaption><\/figure>\n\n\n\n<p>Hace poco m\u00e1s de una semana, Juli\u00e1n \u00c1lvarez tambi\u00e9n habl\u00f3 sobre su adaptaci\u00f3n al equipo: <em><strong>\u201cLlevo pocas semanas entrenando. De a poco voy agarrando lo que quiere \u00e9l<\/strong>&nbsp;(Simeone), lo que quiere el equipo y lo que necesita el equipo de m\u00ed.&nbsp;<strong>Estoy adapt\u00e1ndome<\/strong>, me han ayudado mucho. Vamos por ese camino\u201d<\/em>,&nbsp;<strong>declar\u00f3 en la Argentina previo al comienzo de la doble fecha FIFA de las Eliminatorias Sudamericanas<\/strong>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-1024x684.jpg\" alt=\"Juli\u00e1n \u00c1lvarez Atl\u00e9tico Madrid\" class=\"wp-image-27279\" srcset=\"https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-1024x684.jpg 1024w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-300x200.jpg 300w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-768x513.jpg 768w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-1536x1026.jpg 1536w, https:\/\/www.365scores.com\/es\/news\/wp-content\/uploads\/2024\/08\/GettyImages-2168456490-scaled.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Atl\u00e9tico de Madrid vs Valencia: Cu\u00e1ndo es, d\u00f3nde ver y las formaciones del partidazo en La Liga. (Photo By Oscar J. Barroso\/Europa Press via Getty Images)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Con un gracioso, Juli\u00e1n \u00c1lvarez revel\u00f3 su carta en EA FC25<\/h2>\n\n\n\n<p><strong>En un video protagonizado por EA Sports en conjunto con el Atl\u00e9tico de Madrid, Juli\u00e1n \u00c1lvarez revel\u00f3 su carta en el EA FC25. <\/strong>Lo hizo con sus compa\u00f1eros Antoine Griezmann, el de m\u00e1s valoraci\u00f3n del equipo junto a Jan Oblak, C\u00e9sar Azpilicuta, Rodrigo Riquelme y Rodrigo De Paul, su amigo en la Selecci\u00f3n Argentina.<\/p>\n\n\n\n<p><strong>El delantero argentino <\/strong>ex River Plate y Manchester City <strong>tiene una media de 84 de valoraci\u00f3n con las siguientes estad\u00edsticas: 85 de ritmo, 84 de tiro, 80 de pase, 85 de regate, 57 de defensa y 78 de f\u00edsico<\/strong>. Una buena carta para comenzar el juego, pero lejos de estar entre las mejores. <\/p>\n\n\n\n<blockquote class=\"twitter-tweet\" data-media-max-width=\"560\"><p lang=\"es\" dir=\"ltr\">Retamos a nuestros jugadores a que reconozcan sus ratings en <a href=\"https:\/\/twitter.com\/hashtag\/FC25?src=hash&amp;ref_src=twsrc%5Etfw\" rel=\"noopener\">#FC25<\/a>. \u00bfLo conseguir\u00e1n? ?<br><br>? \u00a1Res\u00e9rvalo ya!: <a href=\"https:\/\/t.co\/tggGnLxxDQ\">https:\/\/t.co\/tggGnLxxDQ<\/a> <a href=\"https:\/\/t.co\/eS3FxDpCa7\">pic.twitter.com\/eS3FxDpCa7<\/a><\/p>&mdash; Atl\u00e9tico de Madrid (@Atleti) <a href=\"https:\/\/twitter.com\/Atleti\/status\/1833913531047034901?ref_src=twsrc%5Etfw\" rel=\"noopener\">September 11, 2024<\/a><\/blockquote> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n","protected":false},"excerpt":{"rendered":"<p>En su vuelta a los entrenamientos al Atl\u00e9tico Madrid, Juli\u00e1n \u00c1lvarez, que podr\u00eda llegar a ser suplente ante Valencia el domingo 15\/9 pensando en el debut en la Champions League ante Leipzig el jueves 19\/9 en el C\u00edvitas Metropolitano, recibi\u00f3 muchos elogios y el apoyo del capit\u00e1n y uno de los referentes del equipo: Koke &hellip;<\/p>\n","protected":false},"author":34,"featured_media":26802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,1,3],"tags":[3927],"content-tags":[4007],"class_list":["post-28521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laliga","category-futbol","category-futbolint","tag-julian-alvarez","content-tags-general-news"],"_links":{"self":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts\/28521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/users\/34"}],"replies":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/comments?post=28521"}],"version-history":[{"count":0,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/posts\/28521\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/media\/26802"}],"wp:attachment":[{"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/media?parent=28521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/categories?post=28521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/tags?post=28521"},{"taxonomy":"content-tags","embeddable":true,"href":"https:\/\/www.365scores.com\/es\/news\/wp-json\/wp\/v2\/content-tags?post=28521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}